
{"id":45523,"date":"2025-06-10T14:56:44","date_gmt":"2025-06-10T12:56:44","guid":{"rendered":"https:\/\/tolunacorporate.com\/?p=45523"},"modified":"2025-06-11T10:38:03","modified_gmt":"2025-06-11T08:38:03","slug":"reimagining-insights-2-preis-oder-herkunft-was-deutschen-konsument-innen-wirklich-wichtig-ist-neue-insights-aus-dem-toluna-sentiment-tracker","status":"publish","type":"post","link":"https:\/\/tolunacorporate.com\/de\/reimagining-insights-2-preis-oder-herkunft-was-deutschen-konsument-innen-wirklich-wichtig-ist-neue-insights-aus-dem-toluna-sentiment-tracker\/","title":{"rendered":"Reimagining Insights 2#: Preis oder Herkunft? Was deutschen Konsument: innen wirklich wichtig ist \u2013 neue Insights aus dem Toluna Sentiment Tracker"},"content":{"rendered":"\n<p>Mit dem fortlaufenden <strong>Toluna Sentiment Tracker<\/strong> beleuchten wir regelm\u00e4\u00dfig, wie sich die Einstellungen und Sorgen von Konsument:innen in Deutschland ver\u00e4ndern \u2013 beeinflusst durch Inflation, politische Entwicklungen und wirtschaftliche Unsicherheiten.&nbsp;<\/p>\n\n\n\n<p>Die neuesten Zahlen zeigen: W\u00e4hrend der Preis f\u00fcr viele weiterhin das zentrale Kriterium ist, spielen Werte wie Herkunft und Vertrauen in bestimmte Marken f\u00fcr einige Zielgruppen nach wie vor eine Rolle.&nbsp;<\/p>\n\n\n\n<p><strong>Herkunftsland vs. Preis \u2013 was z\u00e4hlt mehr?<\/strong>&nbsp;<\/p>\n\n\n\n<p>Neu in unserer aktuellen Erhebung ist die Frage nach dem <strong>Verh\u00e4ltnis von Herkunftsland und Preis<\/strong> beim Kauf verschiedenster Produkte \u2013 von Lebensmitteln \u00fcber Technik bis hin zu Haushaltsger\u00e4ten.&nbsp;<\/p>\n\n\n\n<p>Das Ergebnis: <strong>Fast 80\u202f% der Verbraucher:innen geben an, dass f\u00fcr sie der Preis wichtiger ist als das Herkunftsland<\/strong> des Produkts.&nbsp;<\/p>\n\n\n\n<p>Doch ein Blick in die Alterssegmente offenbart Unterschiede:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Auch <strong>Boomer<\/strong> achten mehrheitlich auf den Preis \u2013 aber innerhalb dieser Kohorte gibt es <strong>signifikant mehr Menschen<\/strong>, f\u00fcr die das Herkunftsland <strong>wichtiger<\/strong> ist als bei den j\u00fcngeren Generationen.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die <strong>Gen Z <\/strong>zeigt sich besonders preissensibel und pragmatisch \u2013 Herkunft spielt f\u00fcr sie kaum eine Rolle.&nbsp;<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-1-1-1024x683.jpg\" alt=\"\" class=\"wp-image-45626\" style=\"width:596px\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-1-1-1024x683.jpg 1024w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-1-1-300x200.jpg 300w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-1-1-768x512.jpg 768w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-1-1.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Sentiment Tracker Images &#8211; Slide option1<\/figcaption><\/figure>\n\n\n\n<p><strong>Wof\u00fcr wird aktuell mehr \u2013 und wof\u00fcr weniger \u2013 Geld ausgegeben?<\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>Die Haushaltsausgaben steigen weiter<\/strong>, wobei <strong>Inflation<\/strong> nach wie vor als Hauptgrund genannt wird.&nbsp;<\/p>\n\n\n\n<p><strong>Bereiche mit steigenden Ausgaben:<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lebensmittel&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wohnen \/ Miete&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Haushaltswaren&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>Bereiche mit sinkenden Ausgaben:<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Essen au\u00dfer Haus \/ Takeout&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mode &amp; Bekleidung&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Konsum von alkoholischen Getr\u00e4nken au\u00dfer Haus&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>Sparma\u00dfnahmen der Konsument:innen:<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vor allem durch <strong>Verzicht auf nicht unbedingt notwendige Ausgaben<\/strong> (v.\u202fa. bei Gen X und Boomern)&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Wechsel zu g\u00fcnstigeren Marken &amp; Handelsmarken<\/strong>&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nutzung von Rabatten, Coupons, Loyalty-Programmen und Apps<\/strong> (v.\u202fa. bei Gen Z)&nbsp;<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"1080\" height=\"800\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-3.jpg\" alt=\"\" class=\"wp-image-45594\" style=\"width:596px\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-3.jpg 1080w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-3-300x222.jpg 300w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-3-1024x759.jpg 1024w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-3-768x569.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p>Knapp jede\/r dritte Konsument:in nutzt vermehrt <strong>Gutscheine und Rabatte<\/strong>, insbesondere innerhalb der Generation Z. Am beliebtesten sind hier klassische <strong>Treuekarten-Rabatte\/ Punktesysteme<\/strong> (insbesondere innerhalb der Boomer und Gen X) sowie <strong>Rabatt-Apps von Gesch\u00e4ften<\/strong>. Diese Systeme bieten Handelsunternehmen somit eine gute M\u00f6glichkeit, Konsument:innen langfristig zu binden.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"759\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-2-1-1024x759.jpg\" alt=\"\" class=\"wp-image-45602\" style=\"width:596px\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-2-1-1024x759.jpg 1024w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-2-1-300x222.jpg 300w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-2-1-768x569.jpg 768w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-2-1.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Offen abgefragt zeigt sich dar\u00fcberhinaus, dass sich <strong>Konsument:innen eine gr\u00f6\u00dfere Transparenz bei Preisanpassungen w\u00fcnschen<\/strong> und solche offen kommuniziert auch eher akzeptieren, als versteckte Preiserh\u00f6hungen (Shrinkflation).&nbsp;<\/p>\n\n\n\n<p><strong>Rezessionsangst w\u00e4chst \u2013 aber auch Optimismus<\/strong>&nbsp;<\/p>\n\n\n\n<p>Die Angst vor einer wirtschaftlichen Verschlechterung f\u00e4llt leicht \u2013 <strong>gleichzeitig steigt der Anteil optimistischer Konsument:innen<\/strong> leicht an.&nbsp;<\/p>\n\n\n\n<p><strong>Hauptgr\u00fcnde f\u00fcr steigenden Optimismus &amp; Konsumfreude:<\/strong>&nbsp;<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Sinkende Inflation&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>Attraktive Rabattaktionen&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>Mehr Vertrauen in die Wirtschaftsentwicklung der neuen Regierung unter Bundeskanzler Merz&nbsp;<\/li>\n<\/ol>\n\n\n\n<p><strong>US-Z\u00f6lle \u2013 \u00fcberschaubare Auswirkungen, aber ver\u00e4nderte Wahrnehmung<\/strong>&nbsp;<\/p>\n\n\n\n<p>Obwohl nur wenige Konsument:innen direkte Auswirkungen der <strong>neuen US-Z\u00f6lle<\/strong> sp\u00fcren, geben knapp <strong>60\u202f% an, dass sie dadurch weniger geneigt sind, US-Marken zu kaufen. <\/strong>Auch wenn die Herkunft im Vergleich zum Preis f\u00fcr die Konsument:innen eine untergeordnete Rolle spielt, k\u00f6nnen <strong>heimische Marken gegen\u00fcber US-Marken<\/strong> durch ihre Regionalit\u00e4t dennoch punkten, insbesondere innerhalb der <strong>Produktionsland bewussteren Boomer<\/strong>.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Knapp <strong>jede\/r F\u00fcnte<\/strong> macht sich <strong>gro\u00dfe oder sogar sehr gro\u00dfe Sorgen<\/strong> \u00fcber Auswirkungen der US-Z\u00f6lle auf eigene <strong>Investitionen, Renten oder Ersparnisse<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Auff\u00e4llig:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Boomer <\/strong>zeigen sich dabei am entspanntesten.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Gen X und Millennials<\/strong> \u00e4u\u00dfern h\u00e4ufiger Sorgen.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Frauen<\/strong> sowie <strong>Haushalte mit Kindern<\/strong> sind besonders betroffen \u2013 vermutlich aufgrund h\u00f6herer finanzieller Belastung im Alltag.&nbsp;<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"759\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-4-1-1024x759.jpg\" alt=\"\" class=\"wp-image-45610\" style=\"width:596px\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-4-1-1024x759.jpg 1024w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-4-1-300x222.jpg 300w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-4-1-768x569.jpg 768w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/Image-4-1.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Was bedeutet das f\u00fcr Unternehmen?<\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>Flexibilit\u00e4t in der Preisgestaltung und Incentivierung<\/strong> wird zum Erfolgsfaktor. Gutscheine, Rabatte und gezielte Angebote bieten eine wichtige M\u00f6glichkeit, die Konsumfreude zu stimulieren und <strong>Markentreue in einem preissensiblen Umfeld<\/strong> zu sichern. <strong>Regionalit\u00e4t<\/strong> und <strong>Transparenz<\/strong> k\u00f6nnen <strong>Wettbewerbsvorteile<\/strong> liefern, mit denen sich Marken in Zeiten von wirtschaftlicher Unsicherheit positiv abheben k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<p>\u201eIn Zeiten wirtschaftlicher Unsicherheit entscheiden nicht nur Qualit\u00e4t oder Innovation \u00fcber den Erfolg einer Marke \u2013 sondern auch die F\u00e4higkeit, situativ passende Kaufanreize zu setzen\u201c, sagt <strong>Claudia Gelbe<\/strong>, Managing Director DACH bei Toluna.&nbsp;<br>\u201e<strong>Insights in Echtzeit<\/strong> helfen Marken, schneller auf ver\u00e4nderte Stimmungen und Bed\u00fcrfnisse zu reagieren.\u201c&nbsp;<\/p>\n\n\n\n<p>Aufgrund der unterschiedlich ausgepr\u00e4gten Sorgen um Investitionen, Renten und Ersparnissen, sollten Banken und Versicherungen ihre Werbeaktivit\u00e4t genau auf die <strong>unterschiedlichen Zielgruppen abstimmen <\/strong>und ihre Sorgen entsprechend ansprechen, um diese gezielt abzuholen.&nbsp;<\/p>\n\n\n\n<p><strong>Technologie als Schl\u00fcssel<\/strong>&nbsp;<\/p>\n\n\n\n<p>Toluna setzt dabei auf die Kombination aus <strong>menschlicher Expertise und KI-gest\u00fctzter Technologie<\/strong>:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>QProbe<\/strong> vertieft offene Antworten in Echtzeit und macht qualitative Dimensionen greifbar.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>SmartCloud<\/strong> liefert eine schnelle und zugleich tiefgreifende Themen- und Sentiment-Analyse \u2013 f\u00fcr <strong>Insights, die direkt in Entscheidungsprozesse<\/strong> einflie\u00dfen.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>Neugierig auf mehr?<\/strong>&nbsp;<br>Den vollst\u00e4ndigen Bericht der aktuellen Erhebungswellen senden wir Ihnen gerne zu \u2013 nehmen Sie Kontakt mit uns auf!&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Quellenangabe: Toluna Sentiment Tracker Mai 2025, Deutschland n=1.000 Nat.rep. Sample, nach Alter (18+), Geschlecht und Region&nbsp;<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mit dem fortlaufenden Toluna Sentiment Tracker beleuchten wir regelm\u00e4\u00dfig, wie sich die<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_toluna_hide_sidebar":false,"footnotes":""},"categories":[50,220],"tags":[],"class_list":["post-45523","post","type-post","status-publish","format-standard","hentry","category-blog","category-germany-de","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tolunacorporate.com\/de\/wp-json\/wp\/v2\/posts\/45523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tolunacorporate.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tolunacorporate.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tolunacorporate.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tolunacorporate.com\/de\/wp-json\/wp\/v2\/comments?post=45523"}],"version-history":[{"count":0,"href":"https:\/\/tolunacorporate.com\/de\/wp-json\/wp\/v2\/posts\/45523\/revisions"}],"wp:attachment":[{"href":"https:\/\/tolunacorporate.com\/de\/wp-json\/wp\/v2\/media?parent=45523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tolunacorporate.com\/de\/wp-json\/wp\/v2\/categories?post=45523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tolunacorporate.com\/de\/wp-json\/wp\/v2\/tags?post=45523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}