
{"id":58989,"date":"2026-07-01T13:03:13","date_gmt":"2026-07-01T11:03:13","guid":{"rendered":"https:\/\/tolunacorporate.com\/?page_id=58989"},"modified":"2026-07-01T13:03:13","modified_gmt":"2026-07-01T11:03:13","slug":"a-propos","status":"publish","type":"page","link":"https:\/\/tolunacorporate.com\/fr\/a-propos\/","title":{"rendered":"\u00c0 propos"},"content":{"rendered":"<style>.kb-row-layout-id10360_6eb805-2f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id10360_6eb805-2f > .kt-row-column-wrap) > .wp-block-toluna-column{justify-content:start;}.kb-row-layout-id10360_6eb805-2f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var(--wp--style--global--content-size);padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id10360_6eb805-2f{background-image:url('https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/about-Full-Bleed-Image-1.png');background-size:cover;background-position:53% 44%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id10360_6eb805-2f > .kt-row-layout-overlay{opacity:0.20;background-color:#080808;}@media all and (max-width: 1024px){.kb-row-layout-id10360_6eb805-2f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id10360_6eb805-2f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id10360_6eb805-2f alignfull kt-row-has-bg wp-block-toluna-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.toluna-column10360_1dbe81-32 > .kt-inside-inner-col,.toluna-column10360_1dbe81-32 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_1dbe81-32 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_1dbe81-32 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_1dbe81-32 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_1dbe81-32 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_1dbe81-32{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_1dbe81-32 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.toluna-column10360_1dbe81-32 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_1dbe81-32\"><div class=\"kt-inside-inner-col\"><style>.wp-block-toluna-advancedheading.kt-adv-heading10360_64dfe6-bd, .wp-block-toluna-advancedheading.kt-adv-heading10360_64dfe6-bd[data-kb-block=\"kb-adv-heading10360_64dfe6-bd\"]{max-width:608px;margin-bottom:var(--global-kb-spacing-xs, 1rem);font-size:48px;line-height:56px;font-style:normal;color:#ffffff;}.wp-block-toluna-advancedheading.kt-adv-heading10360_64dfe6-bd mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_64dfe6-bd[data-kb-block=\"kb-adv-heading10360_64dfe6-bd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h1 class=\"kt-adv-heading10360_64dfe6-bd wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_64dfe6-bd\">\u00c0 propos de Toluna<\/h1>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_e7326c-15, .wp-block-toluna-advancedheading.kt-adv-heading10360_e7326c-15[data-kb-block=\"kb-adv-heading10360_e7326c-15\"]{max-width:608px;font-size:var(--global-kb-font-size-md, 1rem);font-style:normal;color:#ffffff;}.wp-block-toluna-advancedheading.kt-adv-heading10360_e7326c-15 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_e7326c-15[data-kb-block=\"kb-adv-heading10360_e7326c-15\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_e7326c-15 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_e7326c-15\"><em>Gr\u00e2ce \u00e0 notre plateforme cl\u00e9 en main, notre panel mondial de consommateurs, une large gamme de solutions et l\u2019expertise de nos \u00e9quipes, nous vous fournissons des insights \u00e0 la demande pour faire grandir votre marque et votre activit\u00e9.<\/em><br><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id10360_304372-df > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id10360_304372-df > .kt-row-column-wrap) > .wp-block-toluna-column{justify-content:start;}.kb-row-layout-id10360_304372-df > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var(--wp--style--global--content-size);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-md, 2rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id10360_304372-df > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id10360_304372-df > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id10360_304372-df > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id10360_304372-df alignfull wp-block-toluna-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.toluna-column10360_3e0bd3-43 > .kt-inside-inner-col,.toluna-column10360_3e0bd3-43 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_3e0bd3-43 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_3e0bd3-43 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_3e0bd3-43 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_3e0bd3-43 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_3e0bd3-43{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_3e0bd3-43 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.toluna-column10360_3e0bd3-43 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_3e0bd3-43\"><div class=\"kt-inside-inner-col\"><style>.wp-block-toluna-advancedheading.kt-adv-heading10360_bf2f3b-94, .wp-block-toluna-advancedheading.kt-adv-heading10360_bf2f3b-94[data-kb-block=\"kb-adv-heading10360_bf2f3b-94\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_bf2f3b-94 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_bf2f3b-94[data-kb-block=\"kb-adv-heading10360_bf2f3b-94\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_bf2f3b-94 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_bf2f3b-94\">Toluna est un&nbsp;<strong>acteur mondial de r\u00e9f\u00e9rence en mati\u00e8re d\u2019\u00e9tudes<\/strong>, qui permet aux plus grandes marques de prendre des d\u00e9cisions strat\u00e9giques bas\u00e9es sur des insights robustes. Depuis 25 ans, nous accompagnons les entreprises pour maximiser leur impact gr\u00e2ce \u00e0 notre plateforme avanc\u00e9e, notre gamme compl\u00e8te de solutions, notre expertise sectorielle approfondie et notre vaste panel de consommateurs.<br><br>Que vous recherchiez une approche en DIY ou un accompagnement sur mesure, nos solutions s\u2019adaptent \u00e0 vos besoins et \u00e0 vos d\u00e9lais, budgets et ressources. Du test cr\u00e9atif au suivi de marque, en passant par l\u2019optimisation du packaging et l\u2019analyse des parcours e-commerce, notre portefeuille de solutions aide les marques \u00e0 stimuler leur croissance, renforcer leur pertinence et accro\u00eetre leur rentabilit\u00e9.<br><br>Avec plus de 40 bureaux \u00e0 travers le monde et des \u00e9tudes men\u00e9es dans plus de 70 pays, nous collaborons avec les plus grandes marques mondiales. En 2024, GRIT nous a class\u00e9s parmi les entreprises les plus innovantes, confirmant ainsi notre position \u00e0 l\u2019avant-garde de l\u2019innovation et de l\u2019excellence en mati\u00e8re d\u2019insights.<\/p>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_2a1bea-25 > .kt-inside-inner-col,.toluna-column10360_2a1bea-25 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_2a1bea-25 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_2a1bea-25 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_2a1bea-25 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_2a1bea-25 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_2a1bea-25{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_2a1bea-25 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.toluna-column10360_2a1bea-25 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_2a1bea-25\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_36eef8-98 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-toluna-image kb-image10360_36eef8-98\"><figure class=\"aligncenter size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"313\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/toluna-icon.png\" alt=\"\" class=\"kb-img wp-image-8945\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/toluna-icon.png 401w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/toluna-icon-300x234.png 300w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/div><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id10360_116d49-12 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id10360_116d49-12 > .kt-row-column-wrap) > .wp-block-toluna-column{justify-content:start;}.kb-row-layout-id10360_116d49-12 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var(--wp--style--global--content-size);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id10360_116d49-12 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id10360_116d49-12 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id10360_116d49-12 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id10360_116d49-12 alignfull has-gravity-blue-background-color kt-row-has-bg wp-block-toluna-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.toluna-column10360_341953-ea > .kt-inside-inner-col,.toluna-column10360_341953-ea > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_341953-ea > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_341953-ea > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_341953-ea > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_341953-ea > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_341953-ea{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_341953-ea > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.toluna-column10360_341953-ea > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_341953-ea\"><div class=\"kt-inside-inner-col\"><style>.wp-block-toluna-advancedheading.kt-adv-heading10360_b27d2d-d2, .wp-block-toluna-advancedheading.kt-adv-heading10360_b27d2d-d2[data-kb-block=\"kb-adv-heading10360_b27d2d-d2\"]{margin-top:0px;text-align:center;font-size:var(--global-kb-font-size-xl, 2rem);line-height:45px;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_b27d2d-d2 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_b27d2d-d2[data-kb-block=\"kb-adv-heading10360_b27d2d-d2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading10360_b27d2d-d2 wp-block-toluna-advancedheading has-toluna-white-color has-text-color\" data-kb-block=\"kb-adv-heading10360_b27d2d-d2\">Notre histoire<\/h2>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_cfdb60-f5, .wp-block-toluna-advancedheading.kt-adv-heading10360_cfdb60-f5[data-kb-block=\"kb-adv-heading10360_cfdb60-f5\"]{max-width:776px;margin-right:auto;margin-left:auto;text-align:center;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_cfdb60-f5 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_cfdb60-f5[data-kb-block=\"kb-adv-heading10360_cfdb60-f5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_cfdb60-f5 wp-block-toluna-advancedheading has-toluna-white-color has-text-color\" data-kb-block=\"kb-adv-heading10360_cfdb60-f5\">Toluna a \u00e9t\u00e9 fond\u00e9e en 2000, avec une ambition claire : permettre aux marques de cr\u00e9er des produits, services et campagnes extraordinaires gr\u00e2ce \u00e0 des insights de pointe. Au fil des ann\u00e9es, nous avons \u00e9volu\u00e9 pour devenir un leader mondial des \u00e9tudes et des insights, offrant \u00e0 nos clients des solutions innovantes, une plateforme technologique performante, un panel mondial engag\u00e9 et une expertise approfondie pour maximiser leur impact.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id10360_0071f7-6c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id10360_0071f7-6c > .kt-row-column-wrap) > .wp-block-toluna-column{justify-content:start;}.kb-row-layout-id10360_0071f7-6c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var(--wp--style--global--content-size);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id10360_0071f7-6c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id10360_0071f7-6c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id10360_0071f7-6c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id10360_0071f7-6c alignfull has-primary-cobalt-fusion-background-color kt-row-has-bg wp-block-toluna-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.toluna-column10360_0f3610-e5 > .kt-inside-inner-col{display:flex;}.toluna-column10360_0f3610-e5 > .kt-inside-inner-col,.toluna-column10360_0f3610-e5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_0f3610-e5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_0f3610-e5 > .kt-inside-inner-col{flex-direction:column;align-items:center;}.toluna-column10360_0f3610-e5 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.toluna-column10360_0f3610-e5 > .kt-inside-inner-col > .wp-block-toluna-advancedgallery{align-self:stretch;}.toluna-column10360_0f3610-e5 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_0f3610-e5 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_0f3610-e5{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_0f3610-e5 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.toluna-column10360_0f3610-e5 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_0f3610-e5\"><div class=\"kt-inside-inner-col\"><style>.wp-block-toluna-advancedheading.kt-adv-heading10360_09b6b0-14, .wp-block-toluna-advancedheading.kt-adv-heading10360_09b6b0-14[data-kb-block=\"kb-adv-heading10360_09b6b0-14\"]{margin-top:0px;text-align:center;font-size:var(--global-kb-font-size-xl, 2rem);line-height:45px;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_09b6b0-14 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_09b6b0-14[data-kb-block=\"kb-adv-heading10360_09b6b0-14\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading10360_09b6b0-14 wp-block-toluna-advancedheading has-toluna-white-color has-text-color\" data-kb-block=\"kb-adv-heading10360_09b6b0-14\">Notre parcours<\/h2>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_872b6b-b8, .wp-block-toluna-advancedheading.kt-adv-heading10360_872b6b-b8[data-kb-block=\"kb-adv-heading10360_872b6b-b8\"]{text-align:center;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_872b6b-b8 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_872b6b-b8[data-kb-block=\"kb-adv-heading10360_872b6b-b8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_872b6b-b8 wp-block-toluna-advancedheading has-toluna-white-color has-text-color\" data-kb-block=\"kb-adv-heading10360_872b6b-b8\">Gr\u00e2ce aux acquisitions strat\u00e9giques de MetrixLab, GutCheck, Harris Interactive et Ku Run Data, Toluna est devenue une r\u00e9f\u00e9rence mondiale en mati\u00e8re d\u2019insights et red\u00e9finit les standards du secteur.<br><br><strong>Ce que cela signifie pour vous :<\/strong><br>Nos experts, technologies innovantes, mod\u00e8les de service flexibles et solutions sur mesure s\u2019appuient sur un panel mondial de premier plan, des m\u00e9thodologies \u00e9prouv\u00e9es et des donn\u00e9es d\u2019une qualit\u00e9 in\u00e9gal\u00e9e pour g\u00e9n\u00e9rer des insights exploitables instantan\u00e9ment et acc\u00e9l\u00e9rer la croissance de votre entreprise.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id10360_eff27d-47 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id10360_eff27d-47 > .kt-row-column-wrap) > .wp-block-toluna-column{justify-content:start;}.kb-row-layout-id10360_eff27d-47 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var(--wp--style--global--content-size);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);padding-left:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id10360_eff27d-47 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id10360_eff27d-47 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id10360_eff27d-47 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id10360_eff27d-47 alignfull wp-block-toluna-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.toluna-column10360_e7e37f-d2 > .kt-inside-inner-col,.toluna-column10360_e7e37f-d2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_e7e37f-d2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_e7e37f-d2 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_e7e37f-d2 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_e7e37f-d2 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_e7e37f-d2{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_e7e37f-d2 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.toluna-column10360_e7e37f-d2 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_e7e37f-d2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-toluna-advancedheading.kt-adv-heading10360_e4cb36-1a, .wp-block-toluna-advancedheading.kt-adv-heading10360_e4cb36-1a[data-kb-block=\"kb-adv-heading10360_e4cb36-1a\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_e4cb36-1a mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_e4cb36-1a[data-kb-block=\"kb-adv-heading10360_e4cb36-1a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading10360_e4cb36-1a wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_e4cb36-1a\">Nos \u00e9quipes<\/h3>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_153661-96, .wp-block-toluna-advancedheading.kt-adv-heading10360_153661-96[data-kb-block=\"kb-adv-heading10360_153661-96\"]{margin-top:0px;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_153661-96 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_153661-96[data-kb-block=\"kb-adv-heading10360_153661-96\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_153661-96 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_153661-96\">Nos collaborateurs sont le c\u0153ur battant de Toluna. Ils incarnent nos valeurs \u00e0 travers le monde entier : collaboration, respect et int\u00e9grit\u00e9. Nous valorisons la diversit\u00e9 des comp\u00e9tences et des perspectives que chacun a \u00e0 nous apporter, et nous nous effor\u00e7ons de cr\u00e9er un impact significatif pour nos clients, nos communaut\u00e9s et nos coll\u00e8gues.<\/p>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_7d7a77-0b > .kt-inside-inner-col,.toluna-column10360_7d7a77-0b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_7d7a77-0b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_7d7a77-0b > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_7d7a77-0b > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_7d7a77-0b > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_7d7a77-0b{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_7d7a77-0b > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.toluna-column10360_7d7a77-0b > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_7d7a77-0b\"><div class=\"kt-inside-inner-col\"><style>.toluna-column10360_7fa218-4b > .kt-inside-inner-col{display:flex;}.toluna-column10360_7fa218-4b > .kt-inside-inner-col,.toluna-column10360_7fa218-4b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_7fa218-4b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-md, 2rem);}.toluna-column10360_7fa218-4b > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}.toluna-column10360_7fa218-4b > .kt-inside-inner-col > *, .toluna-column10360_7fa218-4b > .kt-inside-inner-col > figure.wp-block-image, .toluna-column10360_7fa218-4b > .kt-inside-inner-col > figure.wp-block-toluna-image{margin-top:0px;margin-bottom:0px;}.toluna-column10360_7fa218-4b > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .toluna-column10360_7fa218-4b{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_7fa218-4b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_7fa218-4b > .kt-inside-inner-col{align-items:flex-start;}.toluna-column10360_7fa218-4b > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_7fa218-4b{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .toluna-column10360_7fa218-4b{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_7fa218-4b{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_7fa218-4b > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.toluna-column10360_7fa218-4b > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.toluna-column10360_7fa218-4b > .kt-inside-inner-col > *, .toluna-column10360_7fa218-4b > .kt-inside-inner-col > figure.wp-block-image, .toluna-column10360_7fa218-4b > .kt-inside-inner-col > figure.wp-block-toluna-image{margin-top:0px;margin-bottom:0px;}.toluna-column10360_7fa218-4b > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .toluna-column10360_7fa218-4b{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_7fa218-4b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_7fa218-4b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.toluna-column10360_7fa218-4b > .kt-inside-inner-col{flex-direction:column;align-items:stretch;flex-wrap:nowrap;}.wp-block-toluna-column.kb-section-dir-horizontal.toluna-column10360_7fa218-4b > .kt-inside-inner-col > .wp-block-toluna-infobox{align-self:unset;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_7fa218-4b kb-section-dir-horizontal kb-section-md-dir-horizontal kb-section-sm-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.toluna-column10360_abe320-6b > .kt-inside-inner-col{display:flex;}.toluna-column10360_abe320-6b > .kt-inside-inner-col,.toluna-column10360_abe320-6b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_abe320-6b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_abe320-6b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:flex-start;}.toluna-column10360_abe320-6b > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.toluna-column10360_abe320-6b > .kt-inside-inner-col > .wp-block-toluna-advancedgallery{align-self:stretch;}.toluna-column10360_abe320-6b > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .toluna-column10360_abe320-6b{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_abe320-6b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_abe320-6b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.toluna-column10360_abe320-6b > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_abe320-6b{text-align:center;}.toluna-column10360_abe320-6b{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .toluna-column10360_abe320-6b{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_abe320-6b{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_abe320-6b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.toluna-column10360_abe320-6b > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .toluna-column10360_abe320-6b{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_abe320-6b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_abe320-6b > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.toluna-column10360_abe320-6b > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_abe320-6b\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_7a36d5-ce.kb-image-is-ratio-size, .kb-image10360_7a36d5-ce .kb-image-is-ratio-size{max-width:142px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_7a36d5-ce.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_7a36d5-ce .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_7a36d5-ce{max-width:142px;}.image-is-svg.kb-image10360_7a36d5-ce{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_7a36d5-ce img{width:100%;}.kb-image10360_7a36d5-ce .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_7a36d5-ce size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"284\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-3.png\" alt=\"\" class=\"kb-img wp-image-8987\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-3.png 284w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-3-150x150.png 150w\" sizes=\"auto, (max-width: 284px) 100vw, 284px\" \/><\/div><\/figure>\n\n\n\n<p class=\"has-text-align-left has-lg-font-size wp-block-paragraph\">\u201cJ\u2019ai rejoint MetrixLab parce que je voulais faire partie d\u2019une \u00e9quipe internationale et d\u00e9velopper mes comp\u00e9tences en cr\u00e9ation vid\u00e9o dans un environnement mondial. Je suis ravi de poursuivre l\u2019aventure avec une \u00e9quipe marketing dynamique et j\u2019ai h\u00e2te de continuer \u00e0 faire \u00e9voluer notre mani\u00e8re de communiquer en vid\u00e9o.\u201d<\/p>\n\n\n<style>.wp-block-toluna-image.kb-image10360_c6a43a-15:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:16px;margin-bottom:16px;}.kb-image10360_c6a43a-15.kb-image-is-ratio-size, .kb-image10360_c6a43a-15 .kb-image-is-ratio-size{max-width:74px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_c6a43a-15.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_c6a43a-15 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_c6a43a-15{max-width:74px;}.image-is-svg.kb-image10360_c6a43a-15{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_c6a43a-15 img{width:100%;}.kb-image10360_c6a43a-15 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_c6a43a-15 size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"43\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png\" alt=\"\" class=\"kb-img wp-image-4594\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png 154w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1-150x43.png 150w\" sizes=\"auto, (max-width: 154px) 100vw, 154px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_cc662a-0f, .wp-block-toluna-advancedheading.kt-adv-heading10360_cc662a-0f[data-kb-block=\"kb-adv-heading10360_cc662a-0f\"]{margin-top:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-md, 1rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_cc662a-0f mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_cc662a-0f[data-kb-block=\"kb-adv-heading10360_cc662a-0f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_cc662a-0f wp-block-toluna-advancedheading has-primary-blue-current-color has-text-color\" data-kb-block=\"kb-adv-heading10360_cc662a-0f\"><strong>Maurits van der Boon<\/strong><\/p>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_f32db9-d3, .wp-block-toluna-advancedheading.kt-adv-heading10360_f32db9-d3[data-kb-block=\"kb-adv-heading10360_f32db9-d3\"]{display:block;text-align:center;font-size:var(--global-kb-font-size-sm, 0.875rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_f32db9-d3 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_f32db9-d3[data-kb-block=\"kb-adv-heading10360_f32db9-d3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading10360_f32db9-d3 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_f32db9-d3\"><strong>Sr. Video &amp; Motion Graphic Designer<\/strong><\/span>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_7806f1-03 > .kt-inside-inner-col{display:flex;}.toluna-column10360_7806f1-03 > .kt-inside-inner-col,.toluna-column10360_7806f1-03 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_7806f1-03 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_7806f1-03 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}.toluna-column10360_7806f1-03 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.toluna-column10360_7806f1-03 > .kt-inside-inner-col > .wp-block-toluna-advancedgallery{align-self:stretch;}.toluna-column10360_7806f1-03 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_7806f1-03 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_7806f1-03{text-align:center;}.toluna-column10360_7806f1-03{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_7806f1-03 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}@media all and (max-width: 767px){.toluna-column10360_7806f1-03 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_7806f1-03\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_9041b4-26.kb-image-is-ratio-size, .kb-image10360_9041b4-26 .kb-image-is-ratio-size{max-width:142px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_9041b4-26.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_9041b4-26 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_9041b4-26{max-width:142px;}.image-is-svg.kb-image10360_9041b4-26{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_9041b4-26 img{width:100%;}.kb-image10360_9041b4-26 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_9041b4-26 size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"284\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-1-1.png\" alt=\"\" class=\"kb-img wp-image-8971\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-1-1.png 285w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-1-1-150x150.png 150w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/div><\/figure>\n\n\n\n<p class=\"has-text-align-left has-lg-font-size wp-block-paragraph\">\u201cL\u2019ambition de chacun de faire progresser et avancer les choses est omnipr\u00e9sente. Les gens encouragent activement le changement et ne se contentent jamais du statu quo. C\u2019est une entreprise tr\u00e8s stimulante dans laquelle travailler.\u201d<\/p>\n\n\n<style>.wp-block-toluna-image.kb-image10360_b3e365-fa:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:16px;margin-bottom:16px;}.kb-image10360_b3e365-fa.kb-image-is-ratio-size, .kb-image10360_b3e365-fa .kb-image-is-ratio-size{max-width:74px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_b3e365-fa.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_b3e365-fa .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_b3e365-fa{max-width:74px;}.image-is-svg.kb-image10360_b3e365-fa{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_b3e365-fa img{width:100%;}.kb-image10360_b3e365-fa .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_b3e365-fa size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"43\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png\" alt=\"\" class=\"kb-img wp-image-4594\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png 154w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1-150x43.png 150w\" sizes=\"auto, (max-width: 154px) 100vw, 154px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_9185c4-67, .wp-block-toluna-advancedheading.kt-adv-heading10360_9185c4-67[data-kb-block=\"kb-adv-heading10360_9185c4-67\"]{margin-top:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-md, 1rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_9185c4-67 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_9185c4-67[data-kb-block=\"kb-adv-heading10360_9185c4-67\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_9185c4-67 wp-block-toluna-advancedheading has-primary-blue-current-color has-text-color\" data-kb-block=\"kb-adv-heading10360_9185c4-67\"><strong>Marie Hense<\/strong><\/p>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_2aab9f-42, .wp-block-toluna-advancedheading.kt-adv-heading10360_2aab9f-42[data-kb-block=\"kb-adv-heading10360_2aab9f-42\"]{display:block;text-align:center;font-size:var(--global-kb-font-size-sm, 0.875rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_2aab9f-42 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_2aab9f-42[data-kb-block=\"kb-adv-heading10360_2aab9f-42\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading10360_2aab9f-42 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_2aab9f-42\"><strong>Global Head of Quality<\/strong><\/span>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_8b5561-b1 > .kt-inside-inner-col{display:flex;}.toluna-column10360_8b5561-b1 > .kt-inside-inner-col,.toluna-column10360_8b5561-b1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_8b5561-b1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_8b5561-b1 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}.toluna-column10360_8b5561-b1 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.toluna-column10360_8b5561-b1 > .kt-inside-inner-col > .wp-block-toluna-advancedgallery{align-self:stretch;}.toluna-column10360_8b5561-b1 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_8b5561-b1 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_8b5561-b1{text-align:center;}.toluna-column10360_8b5561-b1{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_8b5561-b1 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}@media all and (max-width: 767px){.toluna-column10360_8b5561-b1 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_8b5561-b1\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_c2932b-86.kb-image-is-ratio-size, .kb-image10360_c2932b-86 .kb-image-is-ratio-size{max-width:142px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_c2932b-86.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_c2932b-86 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_c2932b-86{max-width:142px;}.image-is-svg.kb-image10360_c2932b-86{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_c2932b-86 img{width:100%;}.kb-image10360_c2932b-86 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_c2932b-86 size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"284\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-2.png\" alt=\"\" class=\"kb-img wp-image-8979\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-2.png 285w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-2-150x150.png 150w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/div><\/figure>\n\n\n\n<p class=\"has-text-align-left has-lg-font-size wp-block-paragraph\">\u201cJ&rsquo;ai toujours eu plaisir \u00e0 travailler chez MetrixLab depuis que j&rsquo;ai rejoint l&rsquo;entreprise, il y 19 ans. C\u2019est l\u2019entreprise la plus dynamique dans laquelle j\u2019ai travaill\u00e9 et elle offre de nombreuses opportunit\u00e9s pour relever de nouveaux d\u00e9fis. J\u2019appr\u00e9cie tout particuli\u00e8rement sa culture entrepreneuriale et l\u2019autonomie qu\u2019elle offre, c\u2019est incroyablement stimulant.\u201d<\/p>\n\n\n<style>.wp-block-toluna-image.kb-image10360_64f6f0-9e:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:16px;margin-bottom:16px;}.kb-image10360_64f6f0-9e.kb-image-is-ratio-size, .kb-image10360_64f6f0-9e .kb-image-is-ratio-size{max-width:74px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_64f6f0-9e.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_64f6f0-9e .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_64f6f0-9e{max-width:74px;}.image-is-svg.kb-image10360_64f6f0-9e{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_64f6f0-9e img{width:100%;}.kb-image10360_64f6f0-9e .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_64f6f0-9e size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"43\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png\" alt=\"\" class=\"kb-img wp-image-4594\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png 154w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1-150x43.png 150w\" sizes=\"auto, (max-width: 154px) 100vw, 154px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_1dadd1-02, .wp-block-toluna-advancedheading.kt-adv-heading10360_1dadd1-02[data-kb-block=\"kb-adv-heading10360_1dadd1-02\"]{margin-top:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-md, 1rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_1dadd1-02 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_1dadd1-02[data-kb-block=\"kb-adv-heading10360_1dadd1-02\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_1dadd1-02 wp-block-toluna-advancedheading has-primary-blue-current-color has-text-color\" data-kb-block=\"kb-adv-heading10360_1dadd1-02\"><strong>Jay Pluhar<\/strong><\/p>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_d6bbb2-af, .wp-block-toluna-advancedheading.kt-adv-heading10360_d6bbb2-af[data-kb-block=\"kb-adv-heading10360_d6bbb2-af\"]{display:block;text-align:center;font-size:var(--global-kb-font-size-sm, 0.875rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_d6bbb2-af mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_d6bbb2-af[data-kb-block=\"kb-adv-heading10360_d6bbb2-af\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading10360_d6bbb2-af wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_d6bbb2-af\"><strong>Senior Solution Consultant<\/strong><\/span>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_eb8118-64 > .kt-inside-inner-col{display:flex;}.toluna-column10360_eb8118-64 > .kt-inside-inner-col,.toluna-column10360_eb8118-64 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_eb8118-64 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-md, 2rem);}.toluna-column10360_eb8118-64 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}.toluna-column10360_eb8118-64 > .kt-inside-inner-col > *, .toluna-column10360_eb8118-64 > .kt-inside-inner-col > figure.wp-block-image, .toluna-column10360_eb8118-64 > .kt-inside-inner-col > figure.wp-block-toluna-image{margin-top:0px;margin-bottom:0px;}.toluna-column10360_eb8118-64 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .toluna-column10360_eb8118-64{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_eb8118-64{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_eb8118-64 > .kt-inside-inner-col{align-items:flex-start;}.toluna-column10360_eb8118-64 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_eb8118-64{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .toluna-column10360_eb8118-64{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_eb8118-64{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_eb8118-64 > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.toluna-column10360_eb8118-64 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.toluna-column10360_eb8118-64 > .kt-inside-inner-col > *, .toluna-column10360_eb8118-64 > .kt-inside-inner-col > figure.wp-block-image, .toluna-column10360_eb8118-64 > .kt-inside-inner-col > figure.wp-block-toluna-image{margin-top:0px;margin-bottom:0px;}.toluna-column10360_eb8118-64 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .toluna-column10360_eb8118-64{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_eb8118-64{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_eb8118-64 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.toluna-column10360_eb8118-64 > .kt-inside-inner-col{flex-direction:column;align-items:stretch;flex-wrap:nowrap;}.wp-block-toluna-column.kb-section-dir-horizontal.toluna-column10360_eb8118-64 > .kt-inside-inner-col > .wp-block-toluna-infobox{align-self:unset;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_eb8118-64 kb-section-dir-horizontal kb-section-md-dir-horizontal kb-section-sm-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.toluna-column10360_274e72-c7 > .kt-inside-inner-col{display:flex;}.toluna-column10360_274e72-c7 > .kt-inside-inner-col,.toluna-column10360_274e72-c7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_274e72-c7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_274e72-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:flex-start;}.toluna-column10360_274e72-c7 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.toluna-column10360_274e72-c7 > .kt-inside-inner-col > .wp-block-toluna-advancedgallery{align-self:stretch;}.toluna-column10360_274e72-c7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .toluna-column10360_274e72-c7{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_274e72-c7{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_274e72-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.toluna-column10360_274e72-c7 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_274e72-c7{text-align:center;}.toluna-column10360_274e72-c7{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .toluna-column10360_274e72-c7{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_274e72-c7{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_274e72-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.toluna-column10360_274e72-c7 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .toluna-column10360_274e72-c7{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_274e72-c7{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_274e72-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.toluna-column10360_274e72-c7 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_274e72-c7\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_5e6684-f5.kb-image-is-ratio-size, .kb-image10360_5e6684-f5 .kb-image-is-ratio-size{max-width:142px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_5e6684-f5.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_5e6684-f5 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_5e6684-f5{max-width:142px;}.image-is-svg.kb-image10360_5e6684-f5{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_5e6684-f5 img{width:100%;}.kb-image10360_5e6684-f5 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_5e6684-f5 size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"284\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-3-1.png\" alt=\"\" class=\"kb-img wp-image-8996\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-3-1.png 284w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-3-1-150x150.png 150w\" sizes=\"auto, (max-width: 284px) 100vw, 284px\" \/><\/div><\/figure>\n\n\n\n<p class=\"has-text-align-left has-lg-font-size wp-block-paragraph\">\u201cLes gens chez Toluna sont formidables. Ils sont accueillants et toujours pr\u00eats \u00e0 aider, m\u00eame lorsqu\u2019il s\u2019agit d\u2019une personne \u00e0 l\u2019autre bout du monde que vous n\u2019avez jamais rencontr\u00e9e.\u201d<\/p>\n\n\n<style>.wp-block-toluna-image.kb-image10360_a97e52-12:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:16px;margin-bottom:16px;}.kb-image10360_a97e52-12.kb-image-is-ratio-size, .kb-image10360_a97e52-12 .kb-image-is-ratio-size{max-width:74px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_a97e52-12.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_a97e52-12 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_a97e52-12{max-width:74px;}.image-is-svg.kb-image10360_a97e52-12{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_a97e52-12 img{width:100%;}.kb-image10360_a97e52-12 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_a97e52-12 size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"43\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png\" alt=\"\" class=\"kb-img wp-image-4594\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png 154w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1-150x43.png 150w\" sizes=\"auto, (max-width: 154px) 100vw, 154px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_d35b7c-22, .wp-block-toluna-advancedheading.kt-adv-heading10360_d35b7c-22[data-kb-block=\"kb-adv-heading10360_d35b7c-22\"]{margin-top:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-md, 1rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_d35b7c-22 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_d35b7c-22[data-kb-block=\"kb-adv-heading10360_d35b7c-22\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_d35b7c-22 wp-block-toluna-advancedheading has-primary-blue-current-color has-text-color\" data-kb-block=\"kb-adv-heading10360_d35b7c-22\"><strong>Stefanie Madison<\/strong><\/p>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_0d7473-f4, .wp-block-toluna-advancedheading.kt-adv-heading10360_0d7473-f4[data-kb-block=\"kb-adv-heading10360_0d7473-f4\"]{display:block;text-align:center;font-size:var(--global-kb-font-size-sm, 0.875rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_0d7473-f4 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_0d7473-f4[data-kb-block=\"kb-adv-heading10360_0d7473-f4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading10360_0d7473-f4 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_0d7473-f4\"><strong>Senior Director, Head of Client Success<\/strong><\/span>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col{display:flex;}.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col,.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col > .wp-block-toluna-advancedgallery{align-self:stretch;}.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_af5cbd-c1{text-align:center;}.toluna-column10360_af5cbd-c1{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}@media all and (max-width: 767px){.toluna-column10360_af5cbd-c1 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_af5cbd-c1\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_9b73a3-51.kb-image-is-ratio-size, .kb-image10360_9b73a3-51 .kb-image-is-ratio-size{max-width:142px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_9b73a3-51.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_9b73a3-51 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_9b73a3-51{max-width:142px;}.image-is-svg.kb-image10360_9b73a3-51{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_9b73a3-51 img{width:100%;}.kb-image10360_9b73a3-51 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_9b73a3-51 size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"284\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-4.png\" alt=\"\" class=\"kb-img wp-image-9004\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-4.png 285w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-4-150x150.png 150w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/div><\/figure>\n\n\n\n<p class=\"has-text-align-left has-lg-font-size wp-block-paragraph\">\u201cPas un seul jour comme un autre en 17 ans d\u2019une aventure extraordinaire, riche en opportunit\u00e9s, en apprentissages et en d\u00e9fis qui m&rsquo;ont constamment pouss\u00e9s \u00e0 me d\u00e9passer \u2014 le tout port\u00e9 par les valeurs, l\u2019innovation et la culture de l\u2019entreprise qui m&rsquo;ont toujours encourag\u00e9s \u00e0 viser l\u2019excellence !\u201d<\/p>\n\n\n<style>.wp-block-toluna-image.kb-image10360_e00625-db:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:16px;margin-bottom:16px;}.kb-image10360_e00625-db.kb-image-is-ratio-size, .kb-image10360_e00625-db .kb-image-is-ratio-size{max-width:74px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_e00625-db.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_e00625-db .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_e00625-db{max-width:74px;}.image-is-svg.kb-image10360_e00625-db{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_e00625-db img{width:100%;}.kb-image10360_e00625-db .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_e00625-db size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"43\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png\" alt=\"\" class=\"kb-img wp-image-4594\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png 154w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1-150x43.png 150w\" sizes=\"auto, (max-width: 154px) 100vw, 154px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_6de379-2b, .wp-block-toluna-advancedheading.kt-adv-heading10360_6de379-2b[data-kb-block=\"kb-adv-heading10360_6de379-2b\"]{margin-top:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-md, 1rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_6de379-2b mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_6de379-2b[data-kb-block=\"kb-adv-heading10360_6de379-2b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_6de379-2b wp-block-toluna-advancedheading has-primary-blue-current-color has-text-color\" data-kb-block=\"kb-adv-heading10360_6de379-2b\"><strong>Sridhar Soma<\/strong><\/p>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_d8ce31-81, .wp-block-toluna-advancedheading.kt-adv-heading10360_d8ce31-81[data-kb-block=\"kb-adv-heading10360_d8ce31-81\"]{display:block;text-align:center;font-size:var(--global-kb-font-size-sm, 0.875rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_d8ce31-81 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_d8ce31-81[data-kb-block=\"kb-adv-heading10360_d8ce31-81\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading10360_d8ce31-81 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_d8ce31-81\"><strong>Associate Director, Research Services<\/strong><\/span>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_d900ef-85 > .kt-inside-inner-col{display:flex;}.toluna-column10360_d900ef-85 > .kt-inside-inner-col,.toluna-column10360_d900ef-85 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_d900ef-85 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_d900ef-85 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}.toluna-column10360_d900ef-85 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.toluna-column10360_d900ef-85 > .kt-inside-inner-col > .wp-block-toluna-advancedgallery{align-self:stretch;}.toluna-column10360_d900ef-85 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_d900ef-85 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_d900ef-85{text-align:center;}.toluna-column10360_d900ef-85{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_d900ef-85 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}@media all and (max-width: 767px){.toluna-column10360_d900ef-85 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_d900ef-85\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_2795b3-fa.kb-image-is-ratio-size, .kb-image10360_2795b3-fa .kb-image-is-ratio-size{max-width:142px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_2795b3-fa.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_2795b3-fa .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_2795b3-fa{max-width:142px;}.image-is-svg.kb-image10360_2795b3-fa{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_2795b3-fa img{width:100%;}.kb-image10360_2795b3-fa .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_2795b3-fa size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"284\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-5.png\" alt=\"\" class=\"kb-img wp-image-9012\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-5.png 285w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-39278-5-150x150.png 150w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/div><\/figure>\n\n\n\n<p class=\"has-text-align-left has-lg-font-size wp-block-paragraph\">\u201cJ\u2019ai rejoint MetrixLab car je voulais pouvoir d\u00e9velopper mes capacit\u00e9s d&rsquo;analyses gr\u00e2ce \u00e0 des m\u00e9thodologies vari\u00e9es et innovantes, mais surtout pour l\u2019esprit de collaboration que l\u2019entreprise transmet \u2014 en particulier entre les \u00e9quipes r\u00e9parties \u00e0 travers le monde.\u201d<\/p>\n\n\n<style>.wp-block-toluna-image.kb-image10360_103c7c-de:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:16px;margin-bottom:16px;}.kb-image10360_103c7c-de.kb-image-is-ratio-size, .kb-image10360_103c7c-de .kb-image-is-ratio-size{max-width:74px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_103c7c-de.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_103c7c-de .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_103c7c-de{max-width:74px;}.image-is-svg.kb-image10360_103c7c-de{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_103c7c-de img{width:100%;}.kb-image10360_103c7c-de .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_103c7c-de size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"43\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png\" alt=\"\" class=\"kb-img wp-image-4594\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1.png 154w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Group-94-1-150x43.png 150w\" sizes=\"auto, (max-width: 154px) 100vw, 154px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_6bf353-24, .wp-block-toluna-advancedheading.kt-adv-heading10360_6bf353-24[data-kb-block=\"kb-adv-heading10360_6bf353-24\"]{margin-top:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-md, 1rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_6bf353-24 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_6bf353-24[data-kb-block=\"kb-adv-heading10360_6bf353-24\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_6bf353-24 wp-block-toluna-advancedheading has-primary-blue-current-color has-text-color\" data-kb-block=\"kb-adv-heading10360_6bf353-24\"><strong>Stefanny Marquez<\/strong><\/p>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_f5f413-ea, .wp-block-toluna-advancedheading.kt-adv-heading10360_f5f413-ea[data-kb-block=\"kb-adv-heading10360_f5f413-ea\"]{display:block;text-align:center;font-size:var(--global-kb-font-size-sm, 0.875rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_f5f413-ea mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_f5f413-ea[data-kb-block=\"kb-adv-heading10360_f5f413-ea\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading10360_f5f413-ea wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_f5f413-ea\"><strong>Research Manager<\/strong><\/span>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_9fdea1-ea > .kt-inside-inner-col{display:flex;}.toluna-column10360_9fdea1-ea > .kt-inside-inner-col,.toluna-column10360_9fdea1-ea > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_9fdea1-ea > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_9fdea1-ea > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.toluna-column10360_9fdea1-ea > .kt-inside-inner-col > *, .toluna-column10360_9fdea1-ea > .kt-inside-inner-col > figure.wp-block-image, .toluna-column10360_9fdea1-ea > .kt-inside-inner-col > figure.wp-block-toluna-image{margin-top:0px;margin-bottom:0px;}.toluna-column10360_9fdea1-ea > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.toluna-column10360_9fdea1-ea > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_9fdea1-ea{position:relative;}.toluna-column10360_9fdea1-ea, .kt-inside-inner-col > .toluna-column10360_9fdea1-ea:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.toluna-column10360_9fdea1-ea > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;}}@media all and (min-width: 768px) and (max-width: 1024px){.toluna-column10360_9fdea1-ea > .kt-inside-inner-col > *, .toluna-column10360_9fdea1-ea > .kt-inside-inner-col > figure.wp-block-image, .toluna-column10360_9fdea1-ea > .kt-inside-inner-col > figure.wp-block-toluna-image{margin-top:0px;margin-bottom:0px;}.toluna-column10360_9fdea1-ea > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.toluna-column10360_9fdea1-ea > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;}.toluna-column10360_9fdea1-ea > .kt-inside-inner-col > *, .toluna-column10360_9fdea1-ea > .kt-inside-inner-col > figure.wp-block-image, .toluna-column10360_9fdea1-ea > .kt-inside-inner-col > figure.wp-block-toluna-image{margin-top:0px;margin-bottom:0px;}.toluna-column10360_9fdea1-ea > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_9fdea1-ea kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.toluna-column10360_6b84df-b2 > .kt-inside-inner-col,.toluna-column10360_6b84df-b2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_6b84df-b2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_6b84df-b2 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_6b84df-b2 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_6b84df-b2 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_6b84df-b2{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_6b84df-b2 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.toluna-column10360_6b84df-b2 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_6b84df-b2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-toluna-advancedheading.kt-adv-heading10360_fc1af3-43, .wp-block-toluna-advancedheading.kt-adv-heading10360_fc1af3-43[data-kb-block=\"kb-adv-heading10360_fc1af3-43\"]{display:block;text-align:right;font-size:var(--global-kb-font-size-md, 1rem);font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_fc1af3-43 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_fc1af3-43[data-kb-block=\"kb-adv-heading10360_fc1af3-43\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<span class=\"kt-adv-heading10360_fc1af3-43 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_fc1af3-43\">Vous souhaitez nous rejoindre ? D\u00e9couvrez nos offres d\u2019emploi !<\/span>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_8c8b3c-91 > .kt-inside-inner-col,.toluna-column10360_8c8b3c-91 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_8c8b3c-91 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_8c8b3c-91 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_8c8b3c-91 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_8c8b3c-91 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_8c8b3c-91{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_8c8b3c-91 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.toluna-column10360_8c8b3c-91 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_8c8b3c-91\"><div class=\"kt-inside-inner-col\"><style>.wp-block-toluna-advancedbtn.kb-btns10360_03b4d0-7d{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns10360_03b4d0-7d .kt-button{font-weight:normal;font-style:normal;}.kt-btns10360_03b4d0-7d .kt-btn-wrap-0{margin-right:5px;}.wp-block-toluna-advancedbtn.kt-btns10360_03b4d0-7d .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-toluna-advancedbtn.kt-btns10360_03b4d0-7d .kt-btn-wrap-0 .kt-button:hover, .wp-block-toluna-advancedbtn.kt-btns10360_03b4d0-7d .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-toluna-advancedbtn.kt-btns10360_03b4d0-7d .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-toluna-advancedbtn.kt-btns10360_03b4d0-7d .kt-btn-wrap-0 .kt-button:hover, .wp-block-toluna-advancedbtn.kt-btns10360_03b4d0-7d .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-toluna-advancedbtn kb-buttons-wrap kb-btns10360_03b4d0-7d\"><style>ul.menu .wp-block-toluna-advancedbtn .kb-btn10360_0d4b3d-c6.kb-button{width:initial;}@media all and (max-width: 1024px){.kb-btn10360_0d4b3d-c6.kb-button .kb-svg-icon-wrap{display:block;}}<\/style><a class=\"kb-button kt-button button kb-btn10360_0d4b3d-c6 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline kt-btn-has-text-true kt-btn-has-svg-false kt-btn-type-default wp-block-toluna-singlebtn\" href=\"https:\/\/tolunacorporate.com\/?page_id=6837\"><span class=\"kt-btn-inner-text\"><strong><strong>Voir les offres<\/strong><\/strong><\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id10360_d1e1cd-18 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id10360_d1e1cd-18 > .kt-row-column-wrap) > .wp-block-toluna-column{justify-content:start;}.kb-row-layout-id10360_d1e1cd-18 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var(--wp--style--global--content-size);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id10360_d1e1cd-18 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id10360_d1e1cd-18 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id10360_d1e1cd-18 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id10360_d1e1cd-18 alignfull has-whisper-background-color kt-row-has-bg wp-block-toluna-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.toluna-column10360_1ca4d9-39 > .kt-inside-inner-col,.toluna-column10360_1ca4d9-39 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_1ca4d9-39 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_1ca4d9-39 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_1ca4d9-39 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_1ca4d9-39 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_1ca4d9-39{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_1ca4d9-39{text-align:center;}}@media all and (max-width: 1024px){.toluna-column10360_1ca4d9-39 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.toluna-column10360_1ca4d9-39{text-align:left;}.toluna-column10360_1ca4d9-39 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_1ca4d9-39\"><div class=\"kt-inside-inner-col\"><style>.wp-block-toluna-advancedheading.kt-adv-heading10360_05ffdc-64, .wp-block-toluna-advancedheading.kt-adv-heading10360_05ffdc-64[data-kb-block=\"kb-adv-heading10360_05ffdc-64\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-size:var(--global-kb-font-size-xl, 2rem);line-height:45px;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_05ffdc-64 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_05ffdc-64[data-kb-block=\"kb-adv-heading10360_05ffdc-64\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading10360_05ffdc-64 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_05ffdc-64\">Nos valeurs<\/h3>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_eb8df2-b7, .wp-block-toluna-advancedheading.kt-adv-heading10360_eb8df2-b7[data-kb-block=\"kb-adv-heading10360_eb8df2-b7\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_eb8df2-b7 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_eb8df2-b7[data-kb-block=\"kb-adv-heading10360_eb8df2-b7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_eb8df2-b7 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_eb8df2-b7\">Chez Toluna, nos valeurs sont le socle de notre r\u00e9ussite et nous guident au quotidien.<\/p>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_c54eb9-91 > .kt-inside-inner-col{display:flex;}.toluna-column10360_c54eb9-91 > .kt-inside-inner-col,.toluna-column10360_c54eb9-91 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_c54eb9-91 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_c54eb9-91 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}.toluna-column10360_c54eb9-91 > .kt-inside-inner-col > *, .toluna-column10360_c54eb9-91 > .kt-inside-inner-col > figure.wp-block-image, .toluna-column10360_c54eb9-91 > .kt-inside-inner-col > figure.wp-block-toluna-image{margin-top:0px;margin-bottom:0px;}.toluna-column10360_c54eb9-91 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.wp-block-toluna-column.kb-section-dir-horizontal.toluna-column10360_c54eb9-91 > .kt-inside-inner-col > *{flex-basis:10px;}.wp-block-toluna-column.kb-section-dir-horizontal.toluna-column10360_c54eb9-91 > .kt-inside-inner-col > .wp-block-toluna-infobox{width:0px;}.kt-row-column-wrap > .toluna-column10360_c54eb9-91{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_c54eb9-91{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_c54eb9-91 > .kt-inside-inner-col{align-items:flex-start;}.toluna-column10360_c54eb9-91 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_c54eb9-91{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .toluna-column10360_c54eb9-91{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_c54eb9-91{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_c54eb9-91 > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.wp-block-toluna-column.kb-section-dir-horizontal.toluna-column10360_c54eb9-91 > .kt-inside-inner-col > *{flex-basis:282px;}}@media all and (max-width: 1024px){.toluna-column10360_c54eb9-91 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.toluna-column10360_c54eb9-91 > .kt-inside-inner-col > *, .toluna-column10360_c54eb9-91 > .kt-inside-inner-col > figure.wp-block-image, .toluna-column10360_c54eb9-91 > .kt-inside-inner-col > figure.wp-block-toluna-image{margin-top:0px;margin-bottom:0px;}.toluna-column10360_c54eb9-91 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .toluna-column10360_c54eb9-91{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_c54eb9-91{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-toluna-column.toluna-column10360_c54eb9-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.toluna-column10360_c54eb9-91{text-align:center;}.toluna-column10360_c54eb9-91 > .kt-inside-inner-col{flex-direction:column;align-items:center;flex-wrap:nowrap;}.wp-block-toluna-column.kb-section-dir-horizontal.toluna-column10360_c54eb9-91 > .kt-inside-inner-col > *,.wp-block-toluna-column.kb-section-md-dir-vertical.toluna-column10360_c54eb9-91 > .kt-inside-inner-col > *{-webkit-flex:1;flex:1;max-width:100%;}.wp-block-toluna-column.kb-section-dir-horizontal.toluna-column10360_c54eb9-91 > .kt-inside-inner-col > .wp-block-toluna-infobox{width:auto;align-self:unset;align-self:unset;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_c54eb9-91 kb-section-dir-horizontal kb-section-sm-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.toluna-column10360_aaf516-07 > .kt-inside-inner-col,.toluna-column10360_aaf516-07 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_aaf516-07 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_aaf516-07 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_aaf516-07 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_aaf516-07 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_aaf516-07{text-align:center;}.toluna-column10360_aaf516-07{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_aaf516-07 > .kt-inside-inner-col{display:flex;flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.toluna-column10360_aaf516-07 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_aaf516-07\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_6c06ce-90.kb-image-is-ratio-size, .kb-image10360_6c06ce-90 .kb-image-is-ratio-size{max-width:202px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_6c06ce-90.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_6c06ce-90 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_6c06ce-90 figure{max-width:202px;}.kb-image10360_6c06ce-90 .image-is-svg, .kb-image10360_6c06ce-90 .image-is-svg img{width:100%;}.kb-image10360_6c06ce-90 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-toluna-image kb-image10360_6c06ce-90\"><figure class=\"aligncenter size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"404\" height=\"404\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-52.png\" alt=\"\" class=\"kb-img wp-image-5022\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-52.png 404w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-52-300x300.png 300w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-52-150x150.png 150w\" sizes=\"auto, (max-width: 404px) 100vw, 404px\" \/><\/div><\/figure><\/div>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_d6e6e1-a1, .wp-block-toluna-advancedheading.kt-adv-heading10360_d6e6e1-a1[data-kb-block=\"kb-adv-heading10360_d6e6e1-a1\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_d6e6e1-a1 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_d6e6e1-a1[data-kb-block=\"kb-adv-heading10360_d6e6e1-a1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_d6e6e1-a1 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_d6e6e1-a1\">Nous sommes proactifs, respectons nos engagements et communiquons en toute transparence.<\/p>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_ed1fbd-62 > .kt-inside-inner-col,.toluna-column10360_ed1fbd-62 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_ed1fbd-62 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_ed1fbd-62 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_ed1fbd-62 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_ed1fbd-62 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_ed1fbd-62{text-align:center;}.toluna-column10360_ed1fbd-62{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_ed1fbd-62 > .kt-inside-inner-col{display:flex;flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.toluna-column10360_ed1fbd-62 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_ed1fbd-62\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_357076-34.kb-image-is-ratio-size, .kb-image10360_357076-34 .kb-image-is-ratio-size{max-width:202px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_357076-34.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_357076-34 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_357076-34 figure{max-width:202px;}.kb-image10360_357076-34 .image-is-svg, .kb-image10360_357076-34 .image-is-svg img{width:100%;}.kb-image10360_357076-34 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-toluna-image kb-image10360_357076-34\"><figure class=\"aligncenter size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"404\" height=\"404\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-53.png\" alt=\"\" class=\"kb-img wp-image-5054\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-53.png 404w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-53-300x300.png 300w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-53-150x150.png 150w\" sizes=\"auto, (max-width: 404px) 100vw, 404px\" \/><\/div><\/figure><\/div>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_0e3349-45, .wp-block-toluna-advancedheading.kt-adv-heading10360_0e3349-45[data-kb-block=\"kb-adv-heading10360_0e3349-45\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_0e3349-45 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_0e3349-45[data-kb-block=\"kb-adv-heading10360_0e3349-45\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_0e3349-45 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_0e3349-45\">Nous priorisons l\u2019action et sommes sans cesse anim\u00e9s par la recherche de l\u2019excellence.<\/p>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_761eb0-22 > .kt-inside-inner-col,.toluna-column10360_761eb0-22 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_761eb0-22 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_761eb0-22 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_761eb0-22 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_761eb0-22 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_761eb0-22{text-align:center;}.toluna-column10360_761eb0-22{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_761eb0-22 > .kt-inside-inner-col{display:flex;flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.toluna-column10360_761eb0-22 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_761eb0-22\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_cc07f6-cb.kb-image-is-ratio-size, .kb-image10360_cc07f6-cb .kb-image-is-ratio-size{max-width:202px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_cc07f6-cb.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_cc07f6-cb .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_cc07f6-cb figure{max-width:202px;}.kb-image10360_cc07f6-cb .image-is-svg, .kb-image10360_cc07f6-cb .image-is-svg img{width:100%;}.kb-image10360_cc07f6-cb .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-toluna-image kb-image10360_cc07f6-cb\"><figure class=\"aligncenter size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"404\" height=\"404\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-54.png\" alt=\"\" class=\"kb-img wp-image-5046\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-54.png 404w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-54-300x300.png 300w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-54-150x150.png 150w\" sizes=\"auto, (max-width: 404px) 100vw, 404px\" \/><\/div><\/figure><\/div>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_081b72-ed, .wp-block-toluna-advancedheading.kt-adv-heading10360_081b72-ed[data-kb-block=\"kb-adv-heading10360_081b72-ed\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_081b72-ed mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_081b72-ed[data-kb-block=\"kb-adv-heading10360_081b72-ed\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_081b72-ed wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_081b72-ed\">Nous croyons au travail d\u2019\u00e9quipe bas\u00e9 sur le partage, l\u2019entraide et l\u2019ouverture d\u2019esprit.<\/p>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_67df2d-21 > .kt-inside-inner-col,.toluna-column10360_67df2d-21 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_67df2d-21 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_67df2d-21 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_67df2d-21 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_67df2d-21 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_67df2d-21{text-align:center;}.toluna-column10360_67df2d-21{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_67df2d-21 > .kt-inside-inner-col{display:flex;flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.toluna-column10360_67df2d-21 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_67df2d-21\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_ae1d05-f4.kb-image-is-ratio-size, .kb-image10360_ae1d05-f4 .kb-image-is-ratio-size{max-width:202px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_ae1d05-f4.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_ae1d05-f4 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_ae1d05-f4 figure{max-width:202px;}.kb-image10360_ae1d05-f4 .image-is-svg, .kb-image10360_ae1d05-f4 .image-is-svg img{width:100%;}.kb-image10360_ae1d05-f4 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-toluna-image kb-image10360_ae1d05-f4\"><figure class=\"aligncenter size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"404\" height=\"404\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-55.png\" alt=\"\" class=\"kb-img wp-image-5038\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-55.png 404w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-55-300x300.png 300w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-55-150x150.png 150w\" sizes=\"auto, (max-width: 404px) 100vw, 404px\" \/><\/div><\/figure><\/div>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_97a9e0-e2, .wp-block-toluna-advancedheading.kt-adv-heading10360_97a9e0-e2[data-kb-block=\"kb-adv-heading10360_97a9e0-e2\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_97a9e0-e2 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_97a9e0-e2[data-kb-block=\"kb-adv-heading10360_97a9e0-e2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_97a9e0-e2 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_97a9e0-e2\">Nos d\u00e9cisions reposent sur des \u00e9changes et une prise de d\u00e9cision collective et rapide.<\/p>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_1a95da-7b > .kt-inside-inner-col,.toluna-column10360_1a95da-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_1a95da-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_1a95da-7b > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_1a95da-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_1a95da-7b > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_1a95da-7b{text-align:center;}.toluna-column10360_1a95da-7b{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_1a95da-7b > .kt-inside-inner-col{display:flex;flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.toluna-column10360_1a95da-7b > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_1a95da-7b\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_8373cb-c8.kb-image-is-ratio-size, .kb-image10360_8373cb-c8 .kb-image-is-ratio-size{max-width:202px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_8373cb-c8.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_8373cb-c8 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_8373cb-c8 figure{max-width:202px;}.kb-image10360_8373cb-c8 .image-is-svg, .kb-image10360_8373cb-c8 .image-is-svg img{width:100%;}.kb-image10360_8373cb-c8 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-toluna-image kb-image10360_8373cb-c8\"><figure class=\"aligncenter size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"404\" height=\"404\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-56.png\" alt=\"\" class=\"kb-img wp-image-5030\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-56.png 404w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-56-300x300.png 300w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-56-150x150.png 150w\" sizes=\"auto, (max-width: 404px) 100vw, 404px\" \/><\/div><\/figure><\/div>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_d573f3-f1, .wp-block-toluna-advancedheading.kt-adv-heading10360_d573f3-f1[data-kb-block=\"kb-adv-heading10360_d573f3-f1\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_d573f3-f1 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_d573f3-f1[data-kb-block=\"kb-adv-heading10360_d573f3-f1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_d573f3-f1 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_d573f3-f1\">Nous nous effor\u00e7ons de comprendre les besoins des autres et de les valoriser.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id10360_1be238-38 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id10360_1be238-38 > .kt-row-column-wrap) > .wp-block-toluna-column{justify-content:start;}.kb-row-layout-id10360_1be238-38 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var(--wp--style--global--content-size);padding-top:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id10360_1be238-38 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id10360_1be238-38 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id10360_1be238-38 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id10360_1be238-38 alignfull wp-block-toluna-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.toluna-column10360_b31f53-6b > .kt-inside-inner-col,.toluna-column10360_b31f53-6b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_b31f53-6b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_b31f53-6b > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_b31f53-6b > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_b31f53-6b > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_b31f53-6b{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_b31f53-6b{text-align:center;}}@media all and (max-width: 1024px){.toluna-column10360_b31f53-6b > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.toluna-column10360_b31f53-6b{text-align:left;}.toluna-column10360_b31f53-6b > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_b31f53-6b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-toluna-advancedheading.kt-adv-heading10360_d96069-44, .wp-block-toluna-advancedheading.kt-adv-heading10360_d96069-44[data-kb-block=\"kb-adv-heading10360_d96069-44\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-size:var(--global-kb-font-size-xl, 2rem);line-height:45px;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_d96069-44 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_d96069-44[data-kb-block=\"kb-adv-heading10360_d96069-44\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading10360_d96069-44 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_d96069-44\">Notre offre<\/h3>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id10360_634f5b-0c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id10360_634f5b-0c > .kt-row-column-wrap) > .wp-block-toluna-column{justify-content:start;}.kb-row-layout-id10360_634f5b-0c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var(--wp--style--global--content-size);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);}.kb-row-layout-id10360_634f5b-0c > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id10360_634f5b-0c > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id10360_634f5b-0c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id10360_634f5b-0c > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id10360_634f5b-0c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id10360_634f5b-0c > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id10360_634f5b-0c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id10360_634f5b-0c alignfull wp-block-toluna-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.toluna-column10360_bc12c0-65 > .kt-inside-inner-col,.toluna-column10360_bc12c0-65 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_bc12c0-65 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_bc12c0-65 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_bc12c0-65 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_bc12c0-65 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_bc12c0-65{text-align:left;}.toluna-column10360_bc12c0-65{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_bc12c0-65 > .kt-inside-inner-col{display:flex;flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.toluna-column10360_bc12c0-65 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_bc12c0-65\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_6e97ee-0e.kb-image-is-ratio-size, .kb-image10360_6e97ee-0e .kb-image-is-ratio-size{max-width:260px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_6e97ee-0e.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_6e97ee-0e .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_6e97ee-0e{max-width:260px;}.image-is-svg.kb-image10360_6e97ee-0e{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_6e97ee-0e img{width:100%;}.kb-image10360_6e97ee-0e .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_6e97ee-0e size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"545\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/AI-powered-technology-platform.png\" alt=\"\" class=\"kb-img wp-image-9047\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/AI-powered-technology-platform.png 520w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/AI-powered-technology-platform-286x300.png 286w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_a5a5bf-78, .wp-block-toluna-advancedheading.kt-adv-heading10360_a5a5bf-78[data-kb-block=\"kb-adv-heading10360_a5a5bf-78\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-size:var(--global-kb-font-size-lg, 1.5rem);line-height:30px;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_a5a5bf-78 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_a5a5bf-78[data-kb-block=\"kb-adv-heading10360_a5a5bf-78\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h5 class=\"kt-adv-heading10360_a5a5bf-78 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_a5a5bf-78\"><strong>Technologie et plateforme boost\u00e9es par l\u2019IA<\/strong><\/h5>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_087d3c-94, .wp-block-toluna-advancedheading.kt-adv-heading10360_087d3c-94[data-kb-block=\"kb-adv-heading10360_087d3c-94\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_087d3c-94 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_087d3c-94[data-kb-block=\"kb-adv-heading10360_087d3c-94\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_087d3c-94 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_087d3c-94\">Une technologie innovante et une plateforme compl\u00e8te offrant une&nbsp;<strong>flexibilit\u00e9, une rapidit\u00e9 et une profondeur d\u2019analyse<\/strong>&nbsp;in\u00e9gal\u00e9es.<\/p>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_96dcef-53 > .kt-inside-inner-col,.toluna-column10360_96dcef-53 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_96dcef-53 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_96dcef-53 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_96dcef-53 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_96dcef-53 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_96dcef-53{text-align:left;}.toluna-column10360_96dcef-53{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_96dcef-53 > .kt-inside-inner-col{display:flex;flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.toluna-column10360_96dcef-53 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_96dcef-53\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_67f75f-24.kb-image-is-ratio-size, .kb-image10360_67f75f-24 .kb-image-is-ratio-size{max-width:260px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_67f75f-24.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_67f75f-24 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_67f75f-24{max-width:260px;}.image-is-svg.kb-image10360_67f75f-24{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_67f75f-24 img{width:100%;}.kb-image10360_67f75f-24 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_67f75f-24 size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"545\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/End-to-end-agile-solutions.png\" alt=\"\" class=\"kb-img wp-image-9055\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/End-to-end-agile-solutions.png 520w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/End-to-end-agile-solutions-286x300.png 286w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_256062-aa, .wp-block-toluna-advancedheading.kt-adv-heading10360_256062-aa[data-kb-block=\"kb-adv-heading10360_256062-aa\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-size:var(--global-kb-font-size-lg, 1.5rem);line-height:30px;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_256062-aa mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_256062-aa[data-kb-block=\"kb-adv-heading10360_256062-aa\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h5 class=\"kt-adv-heading10360_256062-aa wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_256062-aa\">Solutions<br>agiles<\/h5>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_0c58da-2f, .wp-block-toluna-advancedheading.kt-adv-heading10360_0c58da-2f[data-kb-block=\"kb-adv-heading10360_0c58da-2f\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_0c58da-2f mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_0c58da-2f[data-kb-block=\"kb-adv-heading10360_0c58da-2f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_0c58da-2f wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_0c58da-2f\">Des solutions adapt\u00e9es \u00e0 vos d\u00e9fis, couvrant toutes les phases de la collecte d\u2019insights et tous les mod\u00e8les de service,&nbsp;<strong>du DIY \u00e0 l\u2019accompagnement complet de nos experts<\/strong>.<\/p>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_d0bac1-c6 > .kt-inside-inner-col,.toluna-column10360_d0bac1-c6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_d0bac1-c6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_d0bac1-c6 > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_d0bac1-c6 > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_d0bac1-c6 > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_d0bac1-c6{text-align:left;}.toluna-column10360_d0bac1-c6{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_d0bac1-c6 > .kt-inside-inner-col{display:flex;flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.toluna-column10360_d0bac1-c6 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_d0bac1-c6\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_67bdb1-74.kb-image-is-ratio-size, .kb-image10360_67bdb1-74 .kb-image-is-ratio-size{max-width:260px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_67bdb1-74.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_67bdb1-74 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_67bdb1-74{max-width:260px;}.image-is-svg.kb-image10360_67bdb1-74{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_67bdb1-74 img{width:100%;}.kb-image10360_67bdb1-74 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_67bdb1-74 size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"545\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Global-first-party-panel.png\" alt=\"\" class=\"kb-img wp-image-9063\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Global-first-party-panel.png 520w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Global-first-party-panel-286x300.png 286w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_aa1d6e-4b, .wp-block-toluna-advancedheading.kt-adv-heading10360_aa1d6e-4b[data-kb-block=\"kb-adv-heading10360_aa1d6e-4b\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-size:var(--global-kb-font-size-lg, 1.5rem);line-height:30px;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_aa1d6e-4b mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_aa1d6e-4b[data-kb-block=\"kb-adv-heading10360_aa1d6e-4b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h5 class=\"kt-adv-heading10360_aa1d6e-4b wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_aa1d6e-4b\">Panel international<\/h5>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_9561fd-da, .wp-block-toluna-advancedheading.kt-adv-heading10360_9561fd-da[data-kb-block=\"kb-adv-heading10360_9561fd-da\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_9561fd-da mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_9561fd-da[data-kb-block=\"kb-adv-heading10360_9561fd-da\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_9561fd-da wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_9561fd-da\">Un acc\u00e8s direct \u00e0 plus de&nbsp;<strong>79 millions de consommateurs<\/strong>&nbsp;dans le monde entier, pour vous connecter aux bonnes audiences.<\/p>\n<\/div><\/div>\n\n\n<style>.toluna-column10360_e64cd6-9b > .kt-inside-inner-col,.toluna-column10360_e64cd6-9b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.toluna-column10360_e64cd6-9b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.toluna-column10360_e64cd6-9b > .kt-inside-inner-col{flex-direction:column;}.toluna-column10360_e64cd6-9b > .kt-inside-inner-col > .aligncenter{width:100%;}.toluna-column10360_e64cd6-9b > .kt-inside-inner-col:before{opacity:0.3;}.toluna-column10360_e64cd6-9b{text-align:left;}.toluna-column10360_e64cd6-9b{position:relative;}@media all and (max-width: 1024px){.toluna-column10360_e64cd6-9b > .kt-inside-inner-col{display:flex;flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.toluna-column10360_e64cd6-9b > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-toluna-column toluna-column10360_e64cd6-9b\"><div class=\"kt-inside-inner-col\"><style>.kb-image10360_3ecdcd-f4.kb-image-is-ratio-size, .kb-image10360_3ecdcd-f4 .kb-image-is-ratio-size{max-width:260px;width:100%;}.wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_3ecdcd-f4.kb-image-is-ratio-size, .wp-block-toluna-column > .kt-inside-inner-col > .kb-image10360_3ecdcd-f4 .kb-image-is-ratio-size{align-self:unset;}.kb-image10360_3ecdcd-f4{max-width:260px;}.image-is-svg.kb-image10360_3ecdcd-f4{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image10360_3ecdcd-f4 img{width:100%;}.kb-image10360_3ecdcd-f4 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-toluna-image kb-image10360_3ecdcd-f4 size-full\"><div class=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"545\" src=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-60.png\" alt=\"\" class=\"kb-img wp-image-5066\" srcset=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-60.png 520w, https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/03\/Image-60-286x300.png 286w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_0614b9-e0, .wp-block-toluna-advancedheading.kt-adv-heading10360_0614b9-e0[data-kb-block=\"kb-adv-heading10360_0614b9-e0\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-size:var(--global-kb-font-size-lg, 1.5rem);line-height:30px;font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_0614b9-e0 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_0614b9-e0[data-kb-block=\"kb-adv-heading10360_0614b9-e0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h5 class=\"kt-adv-heading10360_0614b9-e0 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_0614b9-e0\">Partenariat sur mesure<\/h5>\n\n\n<style>.wp-block-toluna-advancedheading.kt-adv-heading10360_c2ee63-23, .wp-block-toluna-advancedheading.kt-adv-heading10360_c2ee63-23[data-kb-block=\"kb-adv-heading10360_c2ee63-23\"]{font-style:normal;}.wp-block-toluna-advancedheading.kt-adv-heading10360_c2ee63-23 mark.kt-highlight, .wp-block-toluna-advancedheading.kt-adv-heading10360_c2ee63-23[data-kb-block=\"kb-adv-heading10360_c2ee63-23\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<p class=\"kt-adv-heading10360_c2ee63-23 wp-block-toluna-advancedheading\" data-kb-block=\"kb-adv-heading10360_c2ee63-23\">Un acc\u00e8s direct \u00e0 plus de&nbsp;<strong>79 millions de consommateurs<\/strong>&nbsp;dans le monde entier, pour vous connecter aux bonnes audiences.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 propos de Toluna Gr\u00e2ce \u00e0 notre plateforme cl\u00e9 en main, notre<\/p>\n","protected":false},"author":71,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_toluna_hide_sidebar":false,"_toluna_use_new_nav":false,"footnotes":""},"class_list":["post-58989","page","type-page","status-publish","hentry","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/pages\/58989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/comments?post=58989"}],"version-history":[{"count":0,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/pages\/58989\/revisions"}],"wp:attachment":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/media?parent=58989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}