
{"id":43459,"date":"2011-06-14T02:38:00","date_gmt":"2011-06-14T00:38:00","guid":{"rendered":"https:\/\/tolunacorporate.com\/?p=43459"},"modified":"2025-06-07T02:42:03","modified_gmt":"2025-06-07T00:42:03","slug":"les-defauts-et-fautes-impardonnables-des-candidats-a-lelection-presidentielle-sondage-harris-interactive-pour-m6-msn-rtl","status":"publish","type":"post","link":"https:\/\/tolunacorporate.com\/fr\/les-defauts-et-fautes-impardonnables-des-candidats-a-lelection-presidentielle-sondage-harris-interactive-pour-m6-msn-rtl\/","title":{"rendered":"Les d\u00e9fauts et \u00ab fautes impardonnables \u00bb des candidats \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle Sondage Harris Interactive pour M6-MSN-RTL"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Les d\u00e9fauts et \u00ab fautes impardonnables \u00bb des candidats \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle<\/h5>\n\n\n\n<p><em>Sondage Harris Interactive pour M6-MSN-RTL<\/em><\/p>\n\n\n\n<p><em>Enqu\u00eate r\u00e9alis\u00e9e en ligne par l\u2019institut Harris Interactive du 7 au 10 juin 2011. Echantillon de 1389 individus issus de l\u2019access panel Harris Interactive, repr\u00e9sentatifs de la population fran\u00e7aise \u00e2g\u00e9e de 18 ans et plus. M\u00e9thode des quotas et redressement appliqu\u00e9e aux variables suivantes : sexe, \u00e2ge, cat\u00e9gorie socioprofessionnelle et r\u00e9gion d\u2019habitation de l\u2019interview\u00e9(e).<\/em><\/p>\n\n\n\n<p><strong>Paris, le 14 juin 2011<\/strong>&nbsp;\u2013 A la demande de M6-MSN-RTL, Harris Interactive a interrog\u00e9 un \u00e9chantillon repr\u00e9sentatif de Fran\u00e7ais afin d\u2019interroger&nbsp;<strong>par la n\u00e9gative la perception qu\u2019ils se font d\u2019un Pr\u00e9sident de la R\u00e9publique<\/strong>&nbsp;: quel serait le pire d\u00e9faut d\u2019un candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle et quels \u00e9carts serait-on pr\u00eat \u00e0 pardonner ou non \u00e0 son candidat favori ?<\/p>\n\n\n\n<p>Ce sondage s\u2019inscrit bien entendu dans un contexte&nbsp;<strong>o\u00f9 les affaires mettant en cause des responsables politiques se multiplient<\/strong>: proc\u00e8s Clearstream, cigares de Christian Blanc, vacances de Mich\u00e8le Alliot-Marie, condamnation de Brice Hortefeux pour injure \u00e0 caract\u00e8re racial, accusation d\u2019agressions sexuelles en direction de Georges Tron\u2026<\/p>\n\n\n\n<p>Quels sont&nbsp;<strong>les principaux enseignements de cette \u00e9tude<\/strong>&nbsp;?<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Le pire d\u00e9faut d\u2019un candidat \u00e0 la pr\u00e9sidence de la R\u00e9publique serait d\u2019\u00eatre \u00ab menteur \u00bb et par extension de ne pas tenir ses promesses<\/strong>, et ce quelle que soit la proximit\u00e9 politique des r\u00e9pondants.<\/li>\n\n\n\n<li>Parmi les actes soumis au jugement des Fran\u00e7ais,\u00a0<strong>seuls deux apparaissent comme non-susceptibles de changer les comportements \u00e9lectoraux<\/strong>\u00a0: ainsi une majorit\u00e9 des r\u00e9pondants affirme pouvoir voter pour leur candidat favori, m\u00eame s\u2019il \u00e9tait av\u00e9r\u00e9\u00a0<strong>qu\u2019il s\u2019\u00e9tait emport\u00e9 contre un de ses adversaires politiques ou qu\u2019il avait \u00e9t\u00e9 infid\u00e8le dans son couple.<\/strong><br>En revanche, les Fran\u00e7ais se montrent plus s\u00e9v\u00e8res \u00e0 l\u2019encontre des autres comportements test\u00e9s. Ainsi, une courte majorit\u00e9 (52%) d\u00e9clare qu\u2019elle ne pourrait probablement ou certainement pas voter pour son candidat favori si celui-ci d\u00e9tenait\u00a0<strong>un compte bancaire \u00e0 l\u2019\u00e9tranger<\/strong>. Faisant \u00e9cho \u00e0 un certain nombre d\u2019\u00ab affaires \u00bb ayant touch\u00e9 des membres du gouvernement, deux-tiers des Fran\u00e7ais indiquent qu\u2019ils ne donneraient pas leur voix \u00e0 leur candidat favori si celui-ci avait pass\u00e9\u00a0<strong>des vacances financ\u00e9es par un Etat jug\u00e9 non d\u00e9mocratique. La consommation fr\u00e9quente d\u2019alcool ou de drogue ou encore des propos racistes, x\u00e9nophobes ou sexistes<\/strong>\u00a0emp\u00eacheraient environ les trois quart des \u00e9lecteurs de voter pour leur candidat favori. Enfin, les fautes les plus r\u00e9dhibitoires consisteraient \u00e0 se rendre coupable\u00a0<strong>d\u2019harc\u00e8lement sexuel ou d\u2019un acte de corruption<\/strong>.<br>Rappelons n\u00e9anmoins que\u00a0<strong>la pratique \u00e9lectorale vient parfois contredire cette exigence affich\u00e9e de moralit\u00e9<\/strong>, puisque des personnalit\u00e9s politiques pourtant condamn\u00e9es en justice sont parfois r\u00e9\u00e9lues.<\/li>\n<\/ol>\n\n\n\n<p>Dans le d\u00e9tail :<\/p>\n\n\n\n<p><strong>Le pire d\u00e9faut d\u2019un candidat \u00e0 la pr\u00e9sidence de la R\u00e9publique serait d\u2019abord de mentir et, par extension, de ne pas tenir ses promesses<\/strong><\/p>\n\n\n\n<p><strong>Spontan\u00e9ment, les Fran\u00e7ais indiquent que le pire d\u00e9faut d\u2019un candidat \u00e0 la pr\u00e9sidence de la R\u00e9publique serait d\u2019\u00eatre \u00ab menteur \u00bb<\/strong>et, par extension, de ne pas \u00ab tenir ses promesses \u00bb une fois arriv\u00e9(e) au pouvoir. Le mensonge appara\u00eet donc nettement comme le d\u00e9faut le plus grave identifi\u00e9 par les Fran\u00e7ais, y compris \u00e0 travers l\u2019emploi de qualificatifs s\u00e9mantiquement proches, comme \u00ab malhonn\u00eate \u00bb, \u00ab hypocrite \u00bb. Cette forte stigmatisation du mensonge rappelle en miroir le portrait-robot du Pr\u00e9sident id\u00e9al dress\u00e9 dans l\u2019enqu\u00eate Harris Interactive-M6-RTL-MSN du 4 mai dernier, o\u00f9 il apparaissait que le Pr\u00e9sident parfait aurait pour principale qualit\u00e9 d\u2019\u00eatre \u00ab honn\u00eate \u00bb . Quelques semaines apr\u00e8s l\u2019effervescence m\u00e9diatique autour de \u00ab l\u2019affaire DSK \u00bb, les r\u00e9ponses ne semblent pas avoir \u00e9t\u00e9 influenc\u00e9es outre mesure par cet \u00e9pisode, puisque&nbsp;<strong>s\u2019il y a certes une personnalit\u00e9 politique qui est utilis\u00e9e par certains comme r\u00e9f\u00e9rence pour d\u00e9finir le pire d\u00e9faut d\u2019un candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle, il s\u2019agit plut\u00f4t du Pr\u00e9sident actuel, Nicolas Sarkozy<\/strong>. Celui-ci est en effet cit\u00e9 nomm\u00e9ment par une proportion importante de Fran\u00e7ais et particuli\u00e8rement de sympathisants de Gauche. De fa\u00e7on plus indirecte, on note que les pires d\u00e9fauts cit\u00e9s pour un candidat font parfois \u00e9cho aux critiques prononc\u00e9es par certains \u00e0 l\u2019\u00e9gard du chef de l\u2019Etat concernant son c\u00f4t\u00e9 \u00ab bling bling \u00bb, ou l\u2019importance qu\u2019il accorderait \u00e0 l\u2019\u00ab argent \u00bb. Dans l\u2019ensemble, on peut souligner que les d\u00e9fauts les plus cit\u00e9s ont davantage trait \u00e0 l\u2019int\u00e9grit\u00e9 morale (\u00ab menteur \u00bb, \u00ab malhonn\u00eate \u00bb) qu\u2019\u00e0 des convictions politiques sp\u00e9cifiques (\u00ab Gauche \u00bb ou \u00ab Droite \u00bb, \u00ab langue de bois \u00bb) ou \u00e0 des consid\u00e9rations objectives (\u00ab incomp\u00e9tent \u00bb, \u00ab programme \u00bb). Notons que les sympathisants de Gauche font un peu plus r\u00e9f\u00e9rence que la moyenne \u00e0 des adjectifs moraux alors que les sympathisants de Droite mobilisent un peu plus les notions d\u2019incomp\u00e9tence et de programme, bien que l\u2019int\u00e9grit\u00e9 morale reste chez tous la premi\u00e8re revendication.&nbsp;<strong>Par leurs r\u00e9ponses spontan\u00e9es, les Fran\u00e7ais t\u00e9moignent donc d\u2019une forte exigence de moralit\u00e9 \u00e0 l\u2019\u00e9gard de leurs candidats.<\/strong><\/p>\n\n\n\n<p><strong>Les comportements qui invalideraient les chances d\u2019un candidat \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle : la corruption et le harc\u00e8lement sexuel sont les deux actes per\u00e7us comme les plus inexcusables<\/strong><\/p>\n\n\n\n<p>Les Fran\u00e7ais, par leurs r\u00e9ponses \u00e0 cette enqu\u00eate, indiquent qu\u2019ils ne voteraient pas pour leur candidat favori \u00e0 n\u2019importe quel prix, notamment en termes d\u2019exigence morale.&nbsp;<strong>Seuls deux possibles sujets de controverse perturberaient peu les Fran\u00e7ais dans leur d\u00e9cision de voter pour leur candidat favori \u00e0 la pr\u00e9sidence de la R\u00e9publique<\/strong>: le fait que ce dernier ait&nbsp;<strong>un moment d\u2019\u00e9nervement contre ses adversaires politiques<\/strong>&nbsp;(82% pourraient quand m\u00eame voter pour lui), ou&nbsp;<strong>une infid\u00e9lit\u00e9 dans son couple<\/strong>&nbsp;(76%), qui est per\u00e7ue par une majorit\u00e9 comme relevant strictement de la vie priv\u00e9e. En revanche,&nbsp;<strong>tous les autres comportements, qu\u2019ils soient moralement litigieux ou juridiquement criminels, sont jug\u00e9s inacceptables par une majorit\u00e9 de Fran\u00e7ais<\/strong>&nbsp;: ainsi, seuls 46% des Fran\u00e7ais pourraient voter pour leur candidat favori s\u2019il s\u2019av\u00e9rait que celui-ci disposait d\u2019un compte bancaire \u00e0 l\u2019\u00e9tranger (contre 52% ne le pouvant pas), 32% s\u2019il passait des vacances pay\u00e9es par un Etat jug\u00e9 non-d\u00e9mocratique (contre 66%), 26% s\u2019il consommait fr\u00e9quemment de l\u2019alcool (contre 72%) et 24% s\u2019il prenait des drogues (contre 75%). Certains \u00ab d\u00e9rapages \u00bb sont \u00e9galement lourds de cons\u00e9quences : seuls 24% continueraient \u00e9galement \u00e0 voter pour un candidat ayant tenu un propos raciste, antis\u00e9mite ou x\u00e9nophobe (contre 75%), et 22% pour un candidat ayant tenu un propos d\u00e9sobligeant \u00e0 l\u2019\u00e9gard des femmes (contre 77%). Enfin,&nbsp;<strong>les deux attitudes jug\u00e9es les plus inadmissibles chez un candidat sont le harc\u00e8lement sexuel<\/strong>&nbsp;(9% continuerait \u00e0 voter pour lui, contre 89% ne le pouvant plus)&nbsp;<strong>et un acte de corruption<\/strong>&nbsp;(6%, contre 92%).<\/p>\n\n\n\n<p>La construction d\u2019un indice synth\u00e9tique permet de voir&nbsp;<strong>qu\u2019un tiers des Fran\u00e7ais ne pardonnerait pas au moins 8 des dix comportements cit\u00e9s<\/strong>&nbsp;(36% des femmes, 38% des 50 ans et plus et 40% des sympathisants de Gauche), alors que 11% auraient tendance \u00e0 ne changer de comportement \u00e9lectoral que pour 3 des actes pr\u00e9-cit\u00e9s ou moins.<\/p>\n\n\n\n<p>Si les Fran\u00e7ais se montrent donc en th\u00e9orie intransigeants sur la droiture de leurs candidats, on peut n\u00e9anmoins rappeler que&nbsp;<strong>la pratique \u00e9lectorale vient parfois contredire cette exigence affich\u00e9e de moralit\u00e9<\/strong>, puisque l\u2019on conna\u00eet parfois des exemples de personnalit\u00e9s politiques r\u00e9\u00e9lues apr\u00e8s avoir \u00e9t\u00e9 condamn\u00e9es en justice.<\/p>\n\n\n\n<p>Plus pr\u00e9cis\u00e9ment, on note que les sympathisants de Gauche t\u00e9moignent d\u2019une sensibilit\u00e9 particuli\u00e8re sur certains faits, qu\u2019ils sont plus nombreux que les sympathisants de Droite \u00e0 juger r\u00e9dhibitoires : 61% dans le cas d\u2019un compte bancaire \u00e0 l\u2019\u00e9tranger (contre 37% des sympathisants de Droite), 83% pour des vacances pay\u00e9es par un Etat \u00e9tranger qu\u2019ils jugent non-d\u00e9mocratique (contre 46% \u00e0 Droite), et 91% pour un propos raciste, antis\u00e9mite ou x\u00e9nophobe (contre 65% \u00e0 Droite). Notons que seuls 27% des sympathisants du Front National renonceraient \u00e0 voter pour leur candidat favori dans l\u2019hypoth\u00e8se de la tenue d\u2019un propos raciste. On note en parall\u00e8le une forte sp\u00e9cificit\u00e9 des Fran\u00e7ais ayant l\u2019intention de voter pour Nicolas Sarkozy \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle de 2012, puisque cet \u00e9lectorat potentiel tol\u00e8re nettement mieux le fait d\u2019avoir un compte bancaire \u00e0 l\u2019\u00e9tranger (71% continueraient \u00e0 voter pour ce candidat, pour 46% en moyenne), de se faire payer ses vacances par un Etat non-d\u00e9mocratique (62%, pour 32% en moyenne) ou encore de tenir un propos d\u00e9sobligeant \u00e0 l\u2019\u00e9gard des femmes (38%, dont 22% en moyenne) voire un propos raciste (36%, pour 24% en moyenne).<\/p>\n\n\n\n<p>Par ailleurs, certains faits sont jug\u00e9s davantage r\u00e9dhibitoires par les femmes que par les hommes : la consommation fr\u00e9quente d\u2019alcool (77% des femmes ne pourraient pas voter pour ce candidat, pour 68% des hommes) ou de drogues (78% des femmes pour 70% des hommes), un propos raciste (81% des femmes, pour 68% des hommes) ou d\u00e9sobligeant \u00e0 l\u2019\u00e9gard des femmes (85% des femmes, pour 67% des hommes), ou encore du harc\u00e8lement sexuel (92% des femmes, pour 86% des hommes). Notons \u00e9galement que les cat\u00e9gories populaires sont davantage dissuad\u00e9es de voter pour leur candidat favori par chacun des faits \u00e9voqu\u00e9s que ne le sont les cat\u00e9gories sup\u00e9rieures.<\/p>\n\n\n\n<p>On observe \u00e9galement des effets de g\u00e9n\u00e9ration, puisque les Fran\u00e7ais \u00e2g\u00e9s de 18 \u00e0 24 ans sont moins affect\u00e9s par le fait d\u2019avoir un compte bancaire \u00e0 l\u2019\u00e9tranger (69% continueraient \u00e0 voter pour ce candidat, pour 38% des 50 ans et plus), de se faire payer des vacances par un Etat non-d\u00e9mocratique (44%, pour 32% des 50 ans et plus), d\u2019avoir une consommation fr\u00e9quente d\u2019alcool (33%, pour 20% des 50 ans et plus) ou de drogues (32%, pour 17% des 50 ans et plus).<\/p>\n\n\n\n<p><strong>En savoir plus :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/CP_HIFR_m6msnrtl_14062011.pdf\">Le communiqu\u00e9 de presse<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/resulsts_HIFR_m6msnrtl_14062011.pdf\">L\u2019ensemble des r\u00e9sultats<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les d\u00e9fauts et \u00ab fautes impardonnables \u00bb des candidats \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle<\/p>\n","protected":false},"author":59,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_toluna_hide_sidebar":false,"footnotes":""},"categories":[233],"tags":[101],"class_list":["post-43459","post","type-post","status-publish","format-standard","hentry","category-france-fr","tag-poll-2","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/posts\/43459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/comments?post=43459"}],"version-history":[{"count":0,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/posts\/43459\/revisions"}],"wp:attachment":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/media?parent=43459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/categories?post=43459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/tags?post=43459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}