
{"id":43561,"date":"2011-05-26T02:58:00","date_gmt":"2011-05-26T00:58:00","guid":{"rendered":"https:\/\/tolunacorporate.com\/?p=43561"},"modified":"2025-06-07T03:01:00","modified_gmt":"2025-06-07T01:01:00","slug":"les-modes-dinformation-privilegies-sur-les-evenements-qui-font-lactualite-sondage-harris-interactive-pour-tele2semaines","status":"publish","type":"post","link":"https:\/\/tolunacorporate.com\/fr\/les-modes-dinformation-privilegies-sur-les-evenements-qui-font-lactualite-sondage-harris-interactive-pour-tele2semaines\/","title":{"rendered":"Les modes d\u2019information privil\u00e9gi\u00e9s sur les \u00e9v\u00e9nements qui font l\u2019actualit\u00e9 Sondage Harris Interactive pour T\u00e9l\u00e92Semaines"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Les modes d\u2019information privil\u00e9gi\u00e9s sur les \u00e9v\u00e9nements qui font l\u2019actualit\u00e9<\/h5>\n\n\n\n<p><em>Sondage Harris Interactive pour T\u00e9l\u00e92Semaines<\/em><\/p>\n\n\n\n<p><em>Enqu\u00eate r\u00e9alis\u00e9e en ligne par l\u2019institut Harris Interactive du 20 au 23 mai 2011. Echantillon de 1 001 individus issus de l\u2019access panel Harris Interactive, repr\u00e9sentatifs de la population fran\u00e7aise \u00e2g\u00e9e de 18 ans et plus. M\u00e9thode des quotas et redressement appliqu\u00e9e aux variables suivantes : sexe, \u00e2ge, cat\u00e9gorie socioprofessionnelle et r\u00e9gion d\u2019habitation de l\u2019interview\u00e9(e).<\/em><\/p>\n\n\n\n<p><strong>Paris, le 26 mai 2011<\/strong>&nbsp;\u2014 A la demande de T\u00e9l\u00e92Semaines, Harris Interactive a r\u00e9alis\u00e9&nbsp;<strong>une enqu\u00eate aupr\u00e8s d\u2019un \u00e9chantillon repr\u00e9sentatif de Fran\u00e7ais<\/strong>&nbsp;afin de conna\u00eetre leurs pratiques d\u2019information sur des \u00e9v\u00e9nements qui marquent l\u2019actualit\u00e9, et notamment sur le dernier \u00e9v\u00e9nement de ce type, \u00e0 savoir l\u2019 \u00ab affaire Dominique Strauss-Kahn \u00bb.<\/p>\n\n\n\n<p>L\u2019arrestation de Dominique Strauss-Kahn \u00e0 New-York a suscit\u00e9 dans le monde, et particuli\u00e8rement en France o\u00f9 l\u2019annonce de sa candidature aux primaires socialistes \u00e9tait attendue, une tr\u00e8s forte \u00e9motion collective. Sous le coup de la stupeur et en recherche d\u2019\u00e9l\u00e9ments d\u2019information et d\u2019explication, les Fran\u00e7ais se sont massivement tourn\u00e9s vers les m\u00e9dias. L\u2019information, annonc\u00e9e d\u2019abord sur les r\u00e9seaux sociaux et en premier lieu Twitter, a par la suite largement \u00e9t\u00e9 relay\u00e9e par tous les m\u00e9dias, notamment par les cha\u00eenes d\u2019information en continu ou au cours d\u2019\u00e9missions sp\u00e9ciales. Dans ce contexte, Harris Interactive a fait le point sur le recours aux diff\u00e9rents modes d\u2019information face \u00e0 un tel \u00e9v\u00e9nement, et notamment sur la place de ces cha\u00eenes consacr\u00e9es \u00e0 l\u2019information. Cette enqu\u00eate ne constitue pas une mesure d\u2019audience \u2013 qui r\u00e9pond \u00e0 d\u2019autres protocoles d\u2019interrogation \u2013 mais bien \u00e0 une perception de ce que les Fran\u00e7ais d\u00e9clarent a posteriori avoir regard\u00e9, \u00e0 un moment ou \u00e0 un autre, pour s\u2019informer sur ce sujet. A moins d\u2019un an de l\u2019\u00e9lection pr\u00e9sidentielle, cette enqu\u00eate met en perspective la place des diff\u00e9rents m\u00e9dias dans l\u2019information des citoyens.<\/p>\n\n\n\n<p>Quels sont les&nbsp;<strong>principaux enseignements de cette enqu\u00eate&nbsp;<\/strong>?<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Dans le cas de \u00ab l\u2019affaire Dominique Strauss-Kahn \u00bb,\u00a0<strong>les Fran\u00e7ais d\u00e9clarent avoir largement recours aux journaux t\u00e9l\u00e9vis\u00e9s pour s\u2019informer (77%)<\/strong>, m\u00eame si ce support majoritaire est concurrenc\u00e9 par la radio (66%), Internet (64%) ou les cha\u00eenes d\u2019information en continu (59%).<\/li>\n\n\n\n<li><strong>Parmi les personnes affirmant avoir utilis\u00e9 Internet pour se renseigner sur \u00ab l\u2019affaire DSK \u00bb, la majorit\u00e9 indique s\u2019\u00eatre report\u00e9e sur des supports non-exclusivement num\u00e9riques<\/strong>, comme les sites Internet de journaux papier (60%) ou des sites Internet de cha\u00eenes de t\u00e9l\u00e9vision (37%). Si les sites d\u2019information (Mediapart, Rue89, Slate, Atlantico\u2026) rassemblent tout de m\u00eame 24% de ces individus, les blogs et forums, Facebook et Twitter, pl\u00e9biscit\u00e9s par les journalistes, restent des sources d\u2019information relativement secondaires pour le grand public (respectivement 16%, 13% et 4%).<\/li>\n\n\n\n<li><strong>Parmi les personnes d\u00e9clarant s\u2019\u00eatre renseign\u00e9es via des cha\u00eenes d\u2019information en continu, une majorit\u00e9 d\u00e9clare avoir regard\u00e9 BFM-TV (86%)<\/strong>\u00a0et I-T\u00e9l\u00e9 (62%), devant LCI (31%). De mani\u00e8re g\u00e9n\u00e9rale,\u00a0<strong>67% des Fran\u00e7ais affirment avoir recours \u00e0 des cha\u00eenes d\u2019information en continu lors d\u2019\u00e9v\u00e9nements \u00ab majeurs \u00bb<\/strong>\u00a0et 16% indiquent leur faire plus confiance qu\u2019aux journaux t\u00e9l\u00e9vis\u00e9s (contre 12% qui font plus confiance aux JT).<\/li>\n<\/ol>\n\n\n\n<p>Dans le d\u00e9tail :<\/p>\n\n\n\n<p><strong>Pour s\u2019informer sur la r\u00e9cente \u00ab affaire Dominique Strauss-Kahn \u00bb, les Fran\u00e7ais indiquent avoir surtout utilis\u00e9 les journaux t\u00e9l\u00e9vis\u00e9s, mais \u00e9galement la radio et Internet<\/strong><\/p>\n\n\n\n<p><strong>Pour s\u2019informer sur \u00ab l\u2019affaire Dominique Strauss-Kahn \u00bb, les Fran\u00e7ais indiquent principalement avoir utilis\u00e9 les journaux t\u00e9l\u00e9vis\u00e9s des principales cha\u00eenes hertziennes<\/strong>&nbsp;(TF1, France 2, France 3,\u2026) au cours des derniers jours (77%). Environ deux-tiers des Fran\u00e7ais mentionnent la radio (66%), mais aussi Internet (64%). 59% d\u00e9clarent avoir regard\u00e9 les cha\u00eenes d\u2019information en continu (BFM TV, I-T\u00e9l\u00e9 ou LCI), 50% avoir lu la presse \u00e9crite, nationale ou locale, et 42% s\u2019\u00eatre renseign\u00e9s par le bouche-\u00e0-oreille, pour 36% regardant d\u2019autres types d\u2019\u00e9missions d\u2019information \u00e0 la t\u00e9l\u00e9vision (hors journaux t\u00e9l\u00e9vis\u00e9s).<\/p>\n\n\n\n<p>On note que certains modes d\u2019information sont privil\u00e9gi\u00e9s par des cat\u00e9gories de population : la radio semble avoir davantage \u00e9t\u00e9 \u00e9cout\u00e9e par les hommes (72%, pour 61% des femmes), les cat\u00e9gories sup\u00e9rieures (73%), tandis que le bouche-\u00e0-oreille est davantage cit\u00e9 par les femmes (49%), les cat\u00e9gories populaires (48%), mais aussi les Franciliens (47%).&nbsp;<strong>On rel\u00e8vera enfin que nous n\u2019assistons pas \u00e0 une rupture g\u00e9n\u00e9rationnelle. Internet semble ainsi avoir \u00e9t\u00e9 quasiment autant utilis\u00e9 par toutes les tranches d\u2019\u00e2ge de Fran\u00e7ais<\/strong>&nbsp;Et m\u00eame les plus jeunes (18-24 ans) affirment avoir eu plus recours \u00e0 la t\u00e9l\u00e9vision qu\u2019\u00e0 Internet pour s\u2019informer. Plus g\u00e9n\u00e9ralement, on note que les personnes ne d\u00e9clarant pas de pr\u00e9f\u00e9rence politique particuli\u00e8re sont syst\u00e9matiquement moins nombreuses \u00e0 indiquer avoir utilis\u00e9 chacun des modes d\u2019information cit\u00e9s pour s\u2019informer sur l\u2019affaire Dominique Strauss-Kahn.<\/p>\n\n\n\n<p><strong>Parmi ceux qui ont utilis\u00e9 les cha\u00eenes d\u2019information en continu pour s\u2019informer sur \u00ab l\u2019affaire Dominique Strauss-Kahn \u00bb, BFM-TV et I-T\u00e9l\u00e9 sont bien plus cit\u00e9es que LCI<\/strong><\/p>\n\n\n\n<p><strong>En ce qui concerne plus sp\u00e9cifiquement les cha\u00eenes d\u2019information en continu, parmi les Fran\u00e7ais d\u00e9clarant avoir utilis\u00e9 ce m\u00e9dia pour s\u2019informer sur \u00ab l\u2019affaire DSK \u00bb<\/strong>&nbsp;(soit 59% de l\u2019\u00e9chantillon),&nbsp;<strong>86% indiquent avoir regard\u00e9 BFM TV<\/strong>&nbsp;(dont 40% indiquent l\u2019avoir fait plus que d\u2019habitude), pour 62% citant i&gt;T\u00e9l\u00e9 (dont 25% plus que d\u2019habitude), et 31% LCI (dont 11% plus que d\u2019habitude). i&gt;T\u00e9l\u00e9 est particuli\u00e8rement cit\u00e9 par les hommes (71%, pour 53% des femmes).<\/p>\n\n\n\n<p><strong>Parmi ceux qui ont utilis\u00e9 Internet pour s\u2019informer sur cette affaire, la plupart indiquent avoir consult\u00e9 des sites Internet de journaux papiers \u00ab traditionnels \u00bb<\/strong><\/p>\n\n\n\n<p><strong>Parmi ceux qui d\u00e9clarent s\u2019\u00eatre inform\u00e9s via Internet (soit 64% de l\u2019\u00e9chantillon), une majorit\u00e9 (60%) indique avoir utilis\u00e9 les sites Internet de journaux papiers<\/strong>&nbsp;comme lemonde.fr, lefigaro.fr, etc., dont 25% indiquant les avoir utilis\u00e9s plus que d\u2019habitude (au total, 71% parmi les 18-24 ans et les Franciliens). Plus d\u2019un tiers (37%, dont 15% plus que d\u2019habitude) signale avoir consult\u00e9 les sites Internet de cha\u00eenes de t\u00e9l\u00e9vision, quand pr\u00e8s d\u2019un quart (24%, dont 9% plus que d\u2019habitude) t\u00e9moigne avoir utilis\u00e9 des sites d\u2019information comme Mediapart, Rue89, Slate ou Atlantico (31% parmi les cat\u00e9gories sup\u00e9rieures, et 34% parmi les sympathisants de Gauche). Seuls 16% (dont 6% plus que d\u2019habitude) de ces Fran\u00e7ais s\u2019\u00e9tant renseign\u00e9s par Internet ont utilis\u00e9 des forums ou des blogs, pour 13% (dont 2% plus que d\u2019habitude) ayant utilis\u00e9 Facebook (27% parmi les 18-24 ans), et seulement 4% (dont 2% plus que d\u2019habitude) ayant utilis\u00e9 Twitter.<\/p>\n\n\n\n<p><strong>Si les Fran\u00e7ais sont plus susceptibles de regarder les cha\u00eenes d\u2019information en continu pendant des \u00ab temps forts m\u00e9diatiques \u00bb, ils font n\u00e9anmoins relativement peu confiance aux \u00e9missions d\u2019information \u00e0 la t\u00e9l\u00e9vision, qu\u2019il s\u2019agisse de ces cha\u00eenes d\u2019information en continu ou des journaux t\u00e9l\u00e9vis\u00e9s<\/strong><\/p>\n\n\n\n<p><strong>De fa\u00e7on g\u00e9n\u00e9rale, les deux tiers des Fran\u00e7ais (67%) d\u00e9clarent utiliser les cha\u00eenes d\u2019information en continu pour se renseigner sur les informations qui occupent une place majeure dans l\u2019actualit\u00e9<\/strong>, comme \u00ab l\u2019affaire Dominique Strauss-Kahn \u00bb r\u00e9cemment, les r\u00e9volutions au Proche-Orient ou encore l\u2019accident nucl\u00e9aire de Fukushima (75% parmi les Franciliens, et 77% des sympathisants de Droite). Pr\u00e8s d\u2019un tiers (32%) d\u00e9clare m\u00eame les utiliser plus que d\u2019habitude. 32% n\u2019utilisent pas les cha\u00eenes d\u2019information en continu pour s\u2019informer sur ces enjeux majeurs, dont 19% ne les regardant jamais.<\/p>\n\n\n\n<p>Enfin,&nbsp;<strong>pour s\u2019informer sur ce type d\u2019\u00e9v\u00e9nement, 16% des Fran\u00e7ais d\u00e9clarent faire davantage confiance aux cha\u00eenes d\u2019information en continu<\/strong>&nbsp;(dont 22% des sympathisants de Droite), pour&nbsp;<strong>12% privil\u00e9giant les journaux t\u00e9l\u00e9vis\u00e9s des grandes cha\u00eenes, 31% faisant \u00e9galement confiance aux deux supports, et 40% ne faisant confiance ni \u00e0 l\u2019un, ni \u00e0 l\u2019autre.<\/strong><\/p>\n\n\n\n<p><strong>En savoir plus :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/harris-interactive.fr\/wp-content\/uploads\/sites\/6\/2015\/09\/CP_HIFR_tele2semaines_27050211.pdf\">Le communiqu\u00e9 de pr<\/a><a href=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/CP_HIFR_tele2semaines_27050211.pdf\">e<\/a><a href=\"https:\/\/harris-interactive.fr\/wp-content\/uploads\/sites\/6\/2015\/09\/CP_HIFR_tele2semaines_27050211.pdf\">sse<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/tolunacorporate.com\/wp-content\/uploads\/2025\/06\/results_HIFR_tele2semaines_27050211.pdf\">L\u2019ensemble des r\u00e9sultats<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Les modes d\u2019information privil\u00e9gi\u00e9s sur les \u00e9v\u00e9nements qui font l\u2019actualit\u00e9 Sondage Harris<\/p>\n","protected":false},"author":59,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_toluna_hide_sidebar":false,"footnotes":""},"categories":[233],"tags":[101],"class_list":["post-43561","post","type-post","status-publish","format-standard","hentry","category-france-fr","tag-poll-2","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/posts\/43561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/comments?post=43561"}],"version-history":[{"count":0,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/posts\/43561\/revisions"}],"wp:attachment":[{"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/media?parent=43561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/categories?post=43561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tolunacorporate.com\/fr\/wp-json\/wp\/v2\/tags?post=43561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}